{"id":73,"count":20,"description":"Regroupe les communiqu\u00e9s de presse et les articles parus dans les m\u00e9dias","link":"https:\/\/blogs.editionscle.com\/blogcle\/category\/medias\/","name":"M\u00e9dias","slug":"medias","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>M\u00e9dias Archives - Blog des \u00c9ditions Cl\u00e9<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogs.editionscle.com\/blogcle\/category\/medias\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"M\u00e9dias Archives - Blog des \u00c9ditions Cl\u00e9\" \/>\n<meta property=\"og:description\" content=\"Regroupe les communiqu\u00e9s de presse et les articles parus dans les m\u00e9dias\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogs.editionscle.com\/blogcle\/category\/medias\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog des \u00c9ditions Cl\u00e9\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@editionscle\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/category\\\/medias\\\/\",\"url\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/category\\\/medias\\\/\",\"name\":\"M\u00e9dias Archives - Blog des \u00c9ditions Cl\u00e9\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/category\\\/medias\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/category\\\/medias\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"M\u00e9dias\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/#website\",\"url\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/\",\"name\":\"Blog des \u00c9ditions Cl\u00e9\",\"description\":\"Livres et logiciels pour comprendre la Bible\",\"publisher\":{\"@id\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/#organization\",\"name\":\"Editions Cl\u00e9\",\"url\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/03\\\/Profil_facebookcle.png\",\"contentUrl\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/03\\\/Profil_facebookcle.png\",\"width\":375,\"height\":375,\"caption\":\"Editions Cl\u00e9\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/editionscle\",\"https:\\\/\\\/x.com\\\/editionscle\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/EditionsCle\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"M\u00e9dias Archives - Blog des \u00c9ditions Cl\u00e9","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogs.editionscle.com\/blogcle\/category\/medias\/","og_locale":"fr_FR","og_type":"article","og_title":"M\u00e9dias Archives - Blog des \u00c9ditions Cl\u00e9","og_description":"Regroupe les communiqu\u00e9s de presse et les articles parus dans les m\u00e9dias","og_url":"https:\/\/blogs.editionscle.com\/blogcle\/category\/medias\/","og_site_name":"Blog des \u00c9ditions Cl\u00e9","twitter_card":"summary_large_image","twitter_site":"@editionscle","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/blogs.editionscle.com\/blogcle\/category\/medias\/","url":"https:\/\/blogs.editionscle.com\/blogcle\/category\/medias\/","name":"M\u00e9dias Archives - Blog des \u00c9ditions Cl\u00e9","isPartOf":{"@id":"https:\/\/blogs.editionscle.com\/blogcle\/#website"},"breadcrumb":{"@id":"https:\/\/blogs.editionscle.com\/blogcle\/category\/medias\/#breadcrumb"},"inLanguage":"fr-FR"},{"@type":"BreadcrumbList","@id":"https:\/\/blogs.editionscle.com\/blogcle\/category\/medias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/blogs.editionscle.com\/blogcle\/"},{"@type":"ListItem","position":2,"name":"M\u00e9dias"}]},{"@type":"WebSite","@id":"https:\/\/blogs.editionscle.com\/blogcle\/#website","url":"https:\/\/blogs.editionscle.com\/blogcle\/","name":"Blog des \u00c9ditions Cl\u00e9","description":"Livres et logiciels pour comprendre la Bible","publisher":{"@id":"https:\/\/blogs.editionscle.com\/blogcle\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogs.editionscle.com\/blogcle\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/blogs.editionscle.com\/blogcle\/#organization","name":"Editions Cl\u00e9","url":"https:\/\/blogs.editionscle.com\/blogcle\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blogs.editionscle.com\/blogcle\/#\/schema\/logo\/image\/","url":"https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2018\/03\/Profil_facebookcle.png","contentUrl":"https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2018\/03\/Profil_facebookcle.png","width":375,"height":375,"caption":"Editions Cl\u00e9"},"image":{"@id":"https:\/\/blogs.editionscle.com\/blogcle\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/editionscle","https:\/\/x.com\/editionscle","https:\/\/www.youtube.com\/user\/EditionsCle"]}]}},"_links":{"self":[{"href":"https:\/\/blogs.editionscle.com\/blogcle\/wp-json\/wp\/v2\/categories\/73","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.editionscle.com\/blogcle\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/blogs.editionscle.com\/blogcle\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/blogs.editionscle.com\/blogcle\/wp-json\/wp\/v2\/posts?categories=73"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}