{"id":2021,"date":"2025-12-17T10:44:34","date_gmt":"2025-12-17T09:44:34","guid":{"rendered":"http:\/\/blogs.editionscle.com\/blogcle\/?p=2021"},"modified":"2025-12-17T10:44:35","modified_gmt":"2025-12-17T09:44:35","slug":"une-lumiere-sest-levee-par-timothy-keller-extrait-de-son-livre-noel-cache","status":"publish","type":"post","link":"https:\/\/blogs.editionscle.com\/blogcle\/une-lumiere-sest-levee-par-timothy-keller-extrait-de-son-livre-noel-cache\/","title":{"rendered":"Une lumi\u00e8re s\u2019est lev\u00e9e, par Timothy Keller, extrait de son livre \u00abNo\u00ebl cach\u00e9\u00bb"},"content":{"rendered":"\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"653\" src=\"http:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2019\/12\/Noelcache\u0301_image-1024x653.jpg\" alt=\"\" class=\"wp-image-2022\" srcset=\"https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2019\/12\/Noelcache\u0301_image-1024x653.jpg 1024w, https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2019\/12\/Noelcache\u0301_image-300x191.jpg 300w, https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2019\/12\/Noelcache\u0301_image-768x489.jpg 768w, https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2019\/12\/Noelcache\u0301_image-110x70.jpg 110w, https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2019\/12\/Noelcache\u0301_image-420x268.jpg 420w, https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2019\/12\/Noelcache\u0301_image-675x430.jpg 675w, https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2019\/12\/Noelcache\u0301_image.jpg 1596w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h1 class=\"wp-block-heading\"><a>Chapitre 1 \u2013 Une lumi\u00e8re s\u2019est lev\u00e9e<\/a><\/h1>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Le peuple qui marchait dans les t\u00e9n\u00e8bres a vu une grande lumi\u00e8re, sur ceux qui habitaient le pays de l\u2019ombre de la mort une lumi\u00e8re a brill\u00e9. [\u2026] Oui, toute chaussure port\u00e9e dans la bataille et tout habit roul\u00e9 dans le sang seront livr\u00e9s aux flammes pour \u00eatre r\u00e9duits en cendres. En effet, un enfant nous est n\u00e9, un fils nous est donn\u00e9, et la souverainet\u00e9 reposera sur son \u00e9paule\u00a0; on l\u2019appellera merveilleux conseiller, Dieu puissant, P\u00e8re \u00e9ternel, Prince de la paix. \u00c9tendre la souverainet\u00e9, donner une paix sans fin [\u2026] voil\u00e0 ce que fera le z\u00e8le de l\u2019\u00c9ternel, le ma\u00eetre de l\u2019univers.<\/p>\n<cite>  <br \/>\u00c9sa\u00efe 9.1, 4-6 <br \/><\/cite><\/blockquote>\n\n\n\n<h3 class=\"wp-block-heading\"><em>Des illuminations<\/em><\/h3>\n\n\n\n<p>La mise en place des illuminations est\nl\u2019un des premiers signes de l\u2019arriv\u00e9e de No\u00ebl. D\u00e9corations lumineuses dans les\narbres, bougies aux fen\u00eatres, tout est \u00e9clair\u00e9. Les illuminations de No\u00ebl sur l\u2019Avenue\ndes Champs \u00c9lys\u00e9es restent un ravissement pour ceux qui les regardent, m\u00eame\ndepuis de nombreuses ann\u00e9es. Chaque chose semble envelopp\u00e9e de millions\nd\u2019\u00e9toiles brillantes. Tout cela a du sens, car le 25 d\u00e9cembre suit la nuit la\nplus longue de l\u2019ann\u00e9e dans le monde m\u00e9diterran\u00e9en ainsi qu\u2019en Europe, l\u00e0 o\u00f9\nles f\u00eates de No\u00ebl sont apparues. Mais ces lumi\u00e8res ne sont pas seulement des d\u00e9corations&nbsp;;\nelles sont \u00e9galement un symbole.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">L\u2019obscurit\u00e9 du monde<\/h2>\n\n\n\n<p>Quoi que vous vouliez faire dans un lieu, il y faut de la\nlumi\u00e8re, sinon vous ne voyez rien et ne pouvez pas vous y rep\u00e9rer. No\u00ebl rec\u00e8le\nbien des v\u00e9rit\u00e9s spirituelles, mais il est difficile de les comprendre sans saisir\nd\u2019abord la toute premi\u00e8re&nbsp;: le monde est un lieu obscur, et nous ne\npourrons jamais trouver notre chemin et voir la r\u00e9alit\u00e9, si J\u00e9sus ne nous\n\u00e9claire. Matthieu cite \u00c9sa\u00efe 9.1 et nous dit&nbsp;: \u00ab&nbsp;Le peuple assis dans\nles t\u00e9n\u00e8bres a vu une grande lumi\u00e8re, et sur ceux qui se trouvaient dans le\npays de l\u2019ombre de la mort une lumi\u00e8re s\u2019est lev\u00e9e&nbsp;\u00bb (Matthieu 4.16). Jean\ndit \u00e0 propos de J\u00e9sus que \u00ab&nbsp;cette lumi\u00e8re \u00e9tait la vraie lumi\u00e8re qui, en\nvenant dans le monde \u00e9claire tout \u00eatre humain. Elle \u00e9tait dans le monde et le\nmonde a \u00e9t\u00e9 fait par elle, pourtant le monde ne l\u2019a pas reconnue&nbsp;\u00bb (Jean 1.9-10).<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><em>Mais que signifie \u00ab obscur \u00bb ?<\/em><\/h3>\n\n\n\n<p>Dans la Bible, l\u2019\u00ab obscurit\u00e9 \u00bb fait r\u00e9f\u00e9rence \u00e0 la fois au mal et \u00e0 l\u2019ignorance. Ce mot signifie premi\u00e8rement que le monde est rempli du mal et d\u2019atroces souffrances. Voyez ce qui se passait \u00e0 l\u2019\u00e9poque de la naissance de J\u00e9sus \u2013 violence, injustice, abus de pouvoir, des sans-abri, des r\u00e9fugi\u00e9s fuyant l\u2019oppression, des familles d\u00e9chir\u00e9es, et des douleurs sans fin. Exactement comme aujourd\u2019hui.<\/p>\n\n\n\n<p>L\u2019autre raison pour laquelle notre monde se trouve\n\u00ab&nbsp;dans l\u2019obscurit\u00e9&nbsp;\u00bb est que personne ne sait comment soigner le mal\net la souffrance dont il est rempli. \u00ab&nbsp;Sur ceux qui habitaient le pays de\nl\u2019ombre de la mort une lumi\u00e8re a brill\u00e9&nbsp;\u00bb est un de ces textes lus \u00e0 No\u00ebl,\nque l\u2019on retrouve dans le <em>Messie<\/em> d\u2019Haendel comme l\u2019une des proph\u00e9ties\nsur la naissance de J\u00e9sus (<em>cf.<\/em> \u00c9sa\u00efe 9.1). Cependant, c\u2019est la fin\nd\u2019\u00c9sa\u00efe 8 qui nous explique pourquoi nous avons besoin de la lumi\u00e8re de Dieu.\nAux versets 19-20 nous voyons le peuple invoquer les esprits et les spirites au\nlieu de consulter Dieu. Et le passage se termine ainsi&nbsp;: \u00ab&nbsp;Il\nparcourra le pays, accabl\u00e9 et affam\u00e9 [\u2026] Il regardera vers la terre et il n\u2019y\nverra que d\u00e9tresse, obscurit\u00e9 et sombres angoisses&nbsp;\u00bb (versets 21-22).<\/p>\n\n\n\n<p>Que se passe-t-il l\u00e0&nbsp;? Le peuple \u00ab&nbsp;regarde vers la\nterre&nbsp;\u00bb et cherche des hommes pour soigner le monde. Il s\u2019en remet \u00e0 ses\nexperts, ses mystiques, ses savants, pour trouver des solutions. Il dit, oui\nnous sommes dans l\u2019obscurit\u00e9, mais nous pouvons la vaincre par nos propres\nmoyens. Ce sont les m\u00eames affirmations que nous entendons aujourd\u2019hui. Certains\ns\u2019en remettent \u00e0 l\u2019\u00c9tat, d\u2019autres au march\u00e9, et tous esp\u00e8rent en la\ntechnologie. Ce faisant, ils partent du m\u00eame postulat. Le monde est dans\nl\u2019obscurit\u00e9, mais nous croyons que nous pouvons y mettre fin par notre\nintelligence et notre cr\u00e9ativit\u00e9.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><em>D&rsquo;o\u00f9 vient la lumi\u00e8re ?<\/em><\/h3>\n\n\n\n<p>Il y a quelques ann\u00e9es, j\u2019ai lu dans le <em>New York Times<\/em>\nune publicit\u00e9 qui disait&nbsp;: \u00ab&nbsp;Le message de No\u00ebl est que l\u2019amour\ntriomphera, et que nous r\u00e9ussirons \u00e0 cr\u00e9er un monde d\u2019unit\u00e9 et de paix.&nbsp;\u00bb\nEn d\u2019autres termes, la lumi\u00e8re est <em>en<\/em> <em>nous<\/em>, et donc c\u2019est\nnous qui pouvons dissiper l\u2019obscurit\u00e9 de ce monde.<\/p>\n\n\n\n<p>Vraiment&nbsp;? V\u00e1clav Havel, le premier pr\u00e9sident de la\nR\u00e9publique tch\u00e8que, a \u00e9t\u00e9 l\u2019un des grands penseurs et leaders de la fin du\nvingti\u00e8me si\u00e8cle. Son histoire personnelle lui donnait un regard doublement critique\nsur le communisme et le capitalisme, et il pensait qu\u2019aucun de ces deux r\u00e9gimes\nne pouvait, par lui-m\u00eame, r\u00e9soudre les probl\u00e8mes fondamentaux de l\u2019humanit\u00e9. Il\nsavait que la science, en l\u2019absence de conscience morale, avait men\u00e9 \u00e0\nl\u2019holocauste. Sa conclusion \u00e9tait que ni la technologie, ni l\u2019\u00c9tat, ni le\nmarch\u00e9 seuls ne peuvent nous \u00e9pargner un conflit nucl\u00e9aire, les violences\nethniques ou la d\u00e9gradation de notre environnement. \u00ab&nbsp;La recherche d\u2019une\nvie meilleure ne sauvera pas l\u2019humanit\u00e9, de m\u00eame que la d\u00e9mocratie seule n\u2019y\nsuffira pas&nbsp;\u00bb, affirme V\u00e1clav Havel. \u00ab&nbsp;Il faut se tourner vers Dieu\net le rechercher<a href=\"#_edn1\">[i]<\/a>.&nbsp;\u00bb\nIl ajoute que l\u2019humanit\u00e9 oublie constamment qu\u2019\u00ab&nbsp;elle n\u2019est pas Dieu<a href=\"#_edn2\">[ii]<\/a>&nbsp;\u00bb.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">No\u00ebl et la r\u00e9alit\u00e9<\/h2>\n\n\n\n<p>M\u00eame si le publicitaire du <em>Times<\/em> est sinc\u00e8re, le\nmessage de Christ n\u2019est <em>pas<\/em> que \u00ab&nbsp;nous r\u00e9ussirons \u00e0 cr\u00e9er un\nmonde d\u2019unit\u00e9 et de paix&nbsp;\u00bb. En fait, il est tout le contraire. Pour\nreprendre V\u00e1clav Havel, l\u2019humanit\u00e9 ne peut pas se sauver elle-m\u00eame. Il affirme\nqu\u2019en r\u00e9alit\u00e9, le fait de croire que nous pouvons nous sauver nous-m\u00eames \u2013\nqu\u2019un syst\u00e8me politique ou une id\u00e9ologie peuvent \u00eatre la solution aux probl\u00e8mes\ndes hommes, ne fait qu\u2019augmenter l\u2019obscurit\u00e9. Si, comme le philosophe Bertrand\nRussell, vous pensez qu\u2019il n\u2019y a pas de Dieu, que la r\u00e9alit\u00e9 n\u2019a aucune\ndimension transcendante ou supranaturelle, et que vous vous tournez vers la\nscience pour vous \u00e9clairer, alors les choses deviennent encore plus\nsombres&nbsp;:<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><em>Une vision du monde vide de sens<\/em><\/h3>\n\n\n\n<p>Dans ses grandes lignes, la vision du monde que la\nscience nous offre est telle, et m\u00eame tellement plus vide de sens encore et tellement\nd\u00e9nu\u00e9e de but [\u2026] que l\u2019Homme est le produit de causes sans aucune intention\npr\u00e9alable&nbsp;; que son origine, son d\u00e9veloppement, ses espoirs et ses peurs,\nses amours et ses croyances ne sont que le r\u00e9sultat fortuit de la proximit\u00e9\nentre atomes&nbsp;; qu\u2019aucune flamme, aucun h\u00e9ro\u00efsme, aucune intensit\u00e9 de la\npens\u00e9e ou des sentiments ne peuvent prolonger la vie d\u2019un individu au-del\u00e0 de\nla tombe&nbsp;; que tous ses travaux \u00e0 travers les si\u00e8cles, toute sa ferveur,\ntoute son inspiration, toute la brillance \u00e9clatante de son g\u00e9nie, sont destin\u00e9s\n\u00e0 dispara\u00eetre avec l\u2019effondrement du syst\u00e8me solaire, et que l\u2019ensemble de\nl\u2019\u00e9difice des r\u00e9alisations humaines sera enterr\u00e9 sous les d\u00e9combres d\u2019un\nunivers tomb\u00e9 en ruines [\u2026] Ce n\u2019est qu\u2019en prenant appui sur le cadre de ces\nv\u00e9rit\u00e9s, sur les fermes fondations du d\u00e9sespoir absolu qu\u2019il est envisageable\nde construire une demeure pour l\u2019\u00e2me<a href=\"#_edn3\">[iii]<\/a>.<\/p>\n\n\n\n<p>Quelle noirceur dans cette vision&nbsp;! Elle confirme ce\nque nous avons lu dans \u00c9sa\u00efe 8, c\u2019est-\u00e0-dire que si l\u2019on regarde seulement vers\nla terre et les ressources des hommes, l\u2019obscurit\u00e9 ne peut que s\u2019\u00e9paissir.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><em>Cependant, il y a lieu d\u2019esp\u00e9rer <\/em><\/h3>\n\n\n\n<p>Ainsi donc, No\u00ebl est la fa\u00e7on la plus r\u00e9aliste de consid\u00e9rer\nla vie froidement. No\u00ebl ne dit pas&nbsp;: \u00ab&nbsp;Gardez le sourire&nbsp;! En\ntravaillant tous ensemble, nous pouvons rendre le monde meilleur.&nbsp;\u00bb La\nBible n\u2019invite jamais \u00e0 ignorer les forces de l\u2019obscurit\u00e9, mais uniquement \u00e0 y\nr\u00e9sister&nbsp;; cependant, elle n\u2019entretient aucune illusion sur notre capacit\u00e9\n\u00e0 les vaincre par nous-m\u00eames. Le christianisme n\u2019est pas d\u2019accord avec les penseurs\noptimistes qui soutiennent que \u00ab&nbsp;nous pouvons r\u00e9gler le probl\u00e8me si nous y\ntravaillons s\u00e9rieusement&nbsp;\u00bb. Le christianisme ne soutient pas non plus la\nvision des pessimistes, qui ne pr\u00e9disent qu\u2019un futur catastrophique. Le message\ndu christianisme est plut\u00f4t que \u00ab&nbsp;les choses vont vraiment mal, et nous ne\npouvons pas y rem\u00e9dier ou nous sauver nous-m\u00eames. L\u2019obscurit\u00e9 est grande et <em>cependant<\/em>,\nil y a lieu d\u2019esp\u00e9rer&nbsp;\u00bb. Le message de No\u00ebl est que \u00ab&nbsp;sur ceux qui se\ntrouvaient dans le pays de l\u2019ombre de la mort une lumi\u00e8re s\u2019est lev\u00e9e&nbsp;\u00bb.\nNotez bien qu\u2019il ne dit pas qu\u2019une lumi\u00e8re a jailli du monde, mais qu\u2019une\nlumi\u00e8re s\u2019est lev\u00e9e sur le monde. Elle est venue de l\u2019ext\u00e9rieur. On trouve de\nla lumi\u00e8re \u00e0 l\u2019ext\u00e9rieur de ce monde et J\u00e9sus l\u2019a apport\u00e9e pour nous sauver&nbsp;;\ncar il <em>est<\/em> la Lumi\u00e8re (Jean 8.12).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Ce que la lumi\u00e8re signifie<\/h2>\n\n\n\n<p>\u00c9sa\u00efe utilise la m\u00e9taphore du soleil lorsqu\u2019il parle de la\nlumi\u00e8re de Dieu qui se l\u00e8ve sur un monde obscur. La lumi\u00e8re du soleil apporte\nla <em>vie<\/em>, la <em>v\u00e9rit\u00e9<\/em> et la <em>beaut\u00e9<\/em>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><em>Le soleil nous donne la vie<\/em><\/h3>\n\n\n\n<p>Si le soleil disparaissait, nous serions congel\u00e9s. Le soleil est la source de toute vie. De mani\u00e8re similaire, la Bible affirme que c\u2019est en Dieu seulement que \u00ab nous avons la vie, le mouvement et l\u2019\u00eatre \u00bb (Actes 17.28). Nous n\u2019existons que parce qu\u2019il nous soutient et nous maintient en permanence. Vous lui devez votre \u00eatre. Cela vaut pour votre corps physique, mais aussi pour votre esprit, votre \u00e2me. Selon la Bible, nous avons perdu la relation originelle, pleine et parfaite avec Dieu que nous avions au commencement (Gen\u00e8se 3.1-24). C\u2019est la raison pour laquelle nous conna\u00eetrons la mort physique, et pour laquelle nous sommes actuellement morts spirituellement \u2013 perte de sens et d\u2019esp\u00e9rance, d\u00e9sirs et addictions incontr\u00f4l\u00e9s, profondes attentes qui ne sont jamais satisfaites, hontes et probl\u00e8mes d\u2019identit\u00e9, ajout\u00e9s \u00e0 une incapacit\u00e9 \u00e0 changer tout cela.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><em>Le soleil nous montre la v\u00e9rit\u00e9<\/em><\/h3>\n\n\n\n<p>Lorsque vous conduisez de nuit sans phares, vous prenez le risque d\u2019avoir un accident. Pourquoi cela ? La lumi\u00e8re des phares vous r\u00e9v\u00e8le la vraie nature des choses, comment elles sont r\u00e9ellement. Vous aurez toujours besoin de la plus grande visibilit\u00e9 pour conduire une voiture en toute s\u00e9curit\u00e9. De mani\u00e8re similaire, la Bible d\u00e9clare que Dieu est la source de toute v\u00e9rit\u00e9 (1 Jean 1.5-6). Dieu est la seule raison pour laquelle vous pouvez conna\u00eetre les choses, car il vous a donn\u00e9 une intelligence et des capacit\u00e9s cognitives. Nous ne pouvons conna\u00eetre Dieu s\u2019il ne se r\u00e9v\u00e8le pas \u2013 ce qu\u2019il fait dans la Bible. Vos capacit\u00e9s de raisonnement ne fonctionnent qu\u2019\u00e0 travers lui, et ce n\u2019est qu\u2019\u00e0 travers lui que vous pouvez vraiment comprendre qui il est, et de ce fait qui vous \u00eates : sa cr\u00e9ation.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><em>Le soleil est beaut\u00e9<\/em><\/h3>\n\n\n\n<p><em>L<\/em>La lumi\u00e8re \u00e9blouit et met en joie. Au sens propre. Les habitants des r\u00e9gions dans lesquelles il n\u2019y a que quelques heures d\u2019ensoleillement quotidien \u00e0 certaines p\u00e9riodes de l\u2019ann\u00e9e, ont tendance \u00e0 souffrir de d\u00e9pression. Nous avons besoin de lumi\u00e8re pour \u00eatre joyeux. Comme le note le c\u00e9l\u00e8bre texte de Saint Augustin&nbsp;: \u00ab&nbsp;notre c\u0153ur est inquiet jusqu\u2019\u00e0 ce qu\u2019il repose en vous&nbsp;\u00bb (Confessions 1.1.1). Augustin avait la conviction que lorsque vous pouvez avoir l\u2019impression de tirer votre joie d\u2019autre chose, Dieu est en fait la source r\u00e9elle de cette joie. La chose que vous aimez vient de lui, et vous l\u2019aimez, car elle porte sa marque. Toute joie se trouve en fait en Dieu, et toute autre chose qui peut vous r\u00e9jouir ne fait qu\u2019en d\u00e9river, car ce que vous cherchez r\u00e9ellement, c\u2019est <em>lui<\/em> \u2013 que vous en ayez conscience ou non.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">La lumi\u00e8re se l\u00e8ve<\/h2>\n\n\n\n<p>Ainsi Dieu seul poss\u00e8de la vie,\nla v\u00e9rit\u00e9 et la joie qui nous manquent et que nous ne pouvons produire\nnous-m\u00eames. Comment cette lumi\u00e8re divine peut-elle \u00ab&nbsp;se lever&nbsp;\u00bb, ou\nencore \u00ab&nbsp;briller&nbsp;\u00bb sur nous, comme le dit \u00c9sa\u00efe 9&nbsp;? Les versets\n5 et 6, qui sont les plus connus du chapitre, donnent la r\u00e9ponse de mani\u00e8re\nextr\u00eamement claire. Le texte nous annonce que la lumi\u00e8re est venue, car \u00ab&nbsp;<em>en effet<\/em>, un enfant nous est n\u00e9&nbsp;\u00bb.\nCet enfant l\u2019apporte, car il est le \u00ab&nbsp;merveilleux conseiller, Dieu\npuissant, P\u00e8re \u00e9ternel, Prince de la paix&nbsp;\u00bb. Il est frappant de constater que\nles quatre titres donn\u00e9s \u00e0 cet enfant sont normalement ceux que l\u2019on donne \u00e0 Dieu.\nIl est le Dieu puissant. Il est le P\u00e8re \u00e9ternel, c\u2019est-\u00e0-dire le Cr\u00e9ateur, et\npourtant il est n\u00e9. Rien de tel n\u2019existe dans aucune des autres grandes\nreligions. Il est un \u00eatre humain. Cependant, il n\u2019est pas un simple avatar du\nprincipe divin. Il est Dieu&nbsp;!<\/p>\n\n\n\n<p>C\u2019est bien trop peu de dire que nous \u00ab&nbsp;f\u00eatons&nbsp;\u00bb tout\ncela \u00e0 No\u00ebl. Nous sommes \u00e9blouis, pleins d\u2019admiration, d\u2019amour et de louange.\nDans la suite du livre, nous aborderons les nombreuses implications de la\nnaissance de Dieu dans notre monde. Mentionnons-en deux \u00e0 ce stade.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><em>Si J\u00e9sus-Christ est Dieu&#8230;<\/em><\/h3>\n\n\n\n<p>Pour commencer, si J\u00e9sus-Christ est vraiment le Dieu\npuissant et le P\u00e8re \u00e9ternel, vous ne pouvez pas juste <em>aimer ce qu\u2019il fait<\/em>.\nDans la Bible, ceux qui ont r\u00e9ellement vu et entendu J\u00e9sus n\u2019ont jamais r\u00e9agi faiblement\nou avec indiff\u00e9rence. Apr\u00e8s avoir pris la mesure de ce qu\u2019il disait \u00eatre, ils\nen ont \u00e9t\u00e9 soit effray\u00e9s, soit pris de col\u00e8re contre lui, soit ils se sont mis\n\u00e0 genoux devant lui pour l\u2019adorer. Mais personne ne s\u2019est content\u00e9 de l\u2019appr\u00e9cier.\nPersonne n\u2019a dit&nbsp;: \u00ab&nbsp;Il est si stimulant. Il me donne envie de vivre\nune vie meilleure.&nbsp;\u00bb Si le b\u00e9b\u00e9 n\u00e9 \u00e0 No\u00ebl est le Dieu puissant, alors vous\ndevez le servir en toutes choses. Nous reviendrons sur ce point au chapitre 3.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><em>Si J\u00e9sus est le conseiller&#8230;<\/em><\/h3>\n\n\n\n<p>Ensuite, si J\u00e9sus est le merveilleux conseiller et le Prince\nde la paix, vous devriez <em>vouloir<\/em> le servir. Pourquoi est-il appel\u00e9\n\u00ab&nbsp;conseiller&nbsp;\u00bb&nbsp;? Lorsque vous traversez une \u00e9preuve difficile,\nil est bon de pouvoir s\u2019adresser \u00e0 quelqu\u2019un qui a d\u00e9j\u00e0 parcouru le m\u00eame chemin,\nqui a exp\u00e9riment\u00e9 personnellement ce par quoi vous \u00eates en train de passer. Si\nDieu est vraiment n\u00e9 dans une mangeoire, alors nous avons l\u00e0 quelque chose\nqu\u2019aucune autre religion ne saurait pr\u00e9tendre avoir. C\u2019est-\u00e0-dire un Dieu qui\nvous comprend vraiment, pour \u00eatre pass\u00e9 par les m\u00eames \u00e9preuves. Aucune autre\nreligion ne dit que Dieu a souffert, que Dieu a d\u00fb faire preuve de courage,\nqu\u2019il sait ce que c\u2019est que d\u2019\u00eatre abandonn\u00e9 par ses amis, d\u2019\u00eatre \u00e9cras\u00e9 par\nl\u2019injustice, d\u2019\u00eatre tortur\u00e9 et de mourir. No\u00ebl montre qu\u2019il conna\u00eet les\ndifficult\u00e9s que vous traversez. Lorsque vous lui parlez, il comprend.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><em>L&rsquo;incarnation selon Dorothy Sayers<\/em><\/h3>\n\n\n\n<p>Il y a des ann\u00e9es, l\u2019auteure et romanci\u00e8re anglaise Dorothy\nSayers \u00e9crivait&nbsp;:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>La signification de l\u2019incarnation est que, quelle que soit la raison pour laquelle Dieu a choisi de nous laisser chuter [\u2026] souffrir, \u00eatre la proie du chagrin et de la mort \u2013 il a eu malgr\u00e9 tout l\u2019honn\u00eatet\u00e9 et le courage d\u2019\u00eatre lui-m\u00eame le rem\u00e8de. [\u2026] Il ne peut rien exiger de l\u2019homme qu\u2019il n\u2019ait d\u00e9j\u00e0 exig\u00e9 de lui-m\u00eame. Il a lui-m\u00eame subi tout ce qu\u2019un \u00eatre humain peut subir \u2013 des petites contrari\u00e9t\u00e9s de la vie familiale en passant par les affres d\u2019un travail ext\u00e9nuant ou du manque d\u2019argent, jusqu\u2019aux douleurs les plus atroces, aux humiliations, aux revers, au d\u00e9sespoir et \u00e0 la mort. [\u2026] Il est n\u00e9 dans la mis\u00e8re et [\u2026] a souffert mille morts \u2013 pour nous, en consid\u00e9rant cela comme m\u00e9rit\u00e9<a href=\"#_edn4\">[iv]<\/a>.<\/p>\n<cite> <br \/>Dorothy L. Sayers, \u201cThe Greatest Drama Ever Staged\u201d, <em>Creed or Chaos? And Other Essays in Popular Theology <\/em>(London: Hodder and Stoughton, 1940), p. 6. <\/cite><\/blockquote>\n\n\n\n<h3 class=\"wp-block-heading\"><em>Le merveilleux conseiller&#8230; <\/em><\/h3>\n\n\n\n<p>\u00c9sa\u00efe l\u2019appelle <em>merveilleux<\/em> conseiller pour\nsignifier sa beaut\u00e9. Et peut-\u00eatre est-elle un peu plus \u00e9vidente pour nous\nmaintenant. Il \u00e9tait infiniment \u00e9lev\u00e9, \u00e9tant le Dieu puissant, et pourtant il\nest devenu l\u2019un d\u2019entre nous, entrav\u00e9 par la m\u00eame condition que nous, afin de conna\u00eetre\nla m\u00eame obscurit\u00e9 que nous. Il nous a sauv\u00e9s en montant sur la croix,\nvolontairement, librement, conduit par son immense amour. Voil\u00e0 en quoi c\u2019est\nmerveilleux. Lorsque nous trouvons qu\u2019une chose est merveilleuse, y penser sans\ncesse et ne pas s\u2019en \u00e9loigner est une satisfaction en soi \u2013 et non plus simplement\nun devoir. Ainsi, la raison pour laquelle nous devrions lui\nob\u00e9ir n\u2019est pas seulement que nous le devons et que nous le voulons, elle tient\n\u00e0 ce que, \u00e0 la lumi\u00e8re de tout ce qu\u2019il est et a fait pour nous, il est\nmerveilleux.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><em>J\u00e9sus est la Lumi\u00e8re divine<\/em><\/h3>\n\n\n\n<p>En r\u00e9sum\u00e9, J\u00e9sus est la Lumi\u00e8re divine sur le monde parce\nqu\u2019il apporte une nouvelle vie qui prend la place de notre mort int\u00e9rieure,\nparce qu\u2019il nous montre la v\u00e9rit\u00e9 qui gu\u00e9rit notre c\u00e9cit\u00e9 spirituelle, et parce\nqu\u2019il est la beaut\u00e9 qui nous affranchit de nos addictions \u00e0 l\u2019argent, au sexe\net au pouvoir. Merveilleux conseiller, il marche \u00e0 nos c\u00f4t\u00e9s jusqu\u2019\u00e0 traverser la\nvall\u00e9e de l\u2019ombre de la mort (Matthieu 4.16), l\u00e0 o\u00f9 personne d\u2019autre ne peut\nnous accompagner. Il est notre lumi\u00e8re quand toutes les autres se sont \u00e9teintes<a href=\"#_edn5\">[v]<\/a>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">La lumi\u00e8re de la gr\u00e2ce<\/h2>\n\n\n\n<p>Et donc, comment cette lumi\u00e8re peut-elle devenir la\nn\u00f4tre&nbsp;? Notez que le texte ne dit pas uniquement&nbsp;: \u00ab&nbsp;Un enfant nous est n\u00e9.&nbsp;\u00bb Il dit aussi&nbsp;: \u00ab&nbsp;Un\nfils nous a \u00e9t\u00e9 donn\u00e9.&nbsp;\u00bb Il peut \u00eatre le v\u00f4tre si vous acceptez de le\nrecevoir comme un cadeau de la gr\u00e2ce.<\/p>\n\n\n\n<p>Le verset 4 l\u2019\u00e9voque aussi. Il parle d\u2019une grande bataille\ntout en disant&nbsp;: \u00ab&nbsp;Oui, toute chaussure port\u00e9e dans la bataille et\ntout habit roul\u00e9 dans le sang seront livr\u00e9s aux flammes pour \u00eatre r\u00e9duits en\ncendres.&nbsp;\u00bb Cette image signifie que la victoire compl\u00e8te sur le mal ne\ns\u2019appuie pas sur notre force. Nous n\u2019aurons pas besoin de chaussures de soldat.\nNous n\u2019aurons pas besoin d\u2019armure ou d\u2019\u00e9p\u00e9e. Fondez-les. Brulez-les. C\u2019est un\nautre qui livrera le combat pour vous. Mais qui&nbsp;?<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><em>Un myst\u00e9rieux sauveur<\/em><\/h3>\n\n\n\n<p>\u00c9sa\u00efe ne l\u2019indique pas dans ce texte. Il vous faut attendre\nles \u00ab&nbsp;Chants du Serviteur&nbsp;\u00bb aux chapitres 42-55 pour voir le proph\u00e8te\n\u00e9voquer un myst\u00e9rieux sauveur \u00e0 venir. De lui, il dit&nbsp;: \u00ab&nbsp;Mais lui,\nil \u00e9tait bless\u00e9 \u00e0 cause de nos transgressions, bris\u00e9 \u00e0 cause de nos\nfautes&nbsp;: la punition qui nous donne la paix est tomb\u00e9e sur lui, et c\u2019est\npar ses blessures que nous sommes gu\u00e9ris&nbsp;\u00bb (\u00c9sa\u00efe 53.5). En allant sur la\ncroix, J\u00e9sus a pay\u00e9 le prix de notre p\u00e9ch\u00e9. Si nous mettons notre confiance\ndans l\u2019\u0153uvre accomplie par Dieu plut\u00f4t qu\u2019en nos propres efforts de moralit\u00e9,\nDieu pardonne, nous accueille, et nous donne le Saint-Esprit pour nous\nrenouveler enti\u00e8rement. Ce grand salut, cette lumi\u00e8re qui brille sur nous,\nrempli de vie, de v\u00e9rit\u00e9 et de beaut\u00e9, est un don. La seule mani\u00e8re de le\nrecevoir est de reconna\u00eetre que c\u2019est une gr\u00e2ce que nous ne m\u00e9ritons pas.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><em>Des cadeaux difficiles \u00e0 accepter  <\/em><\/h3>\n\n\n\n<p>\u00c0 No\u00ebl, on re\u00e7oit des cadeaux, mais nous savons que certains\nsont plus difficiles \u00e0 recevoir que d\u2019autres. Il y a des cadeaux qui vont vous blesser\ndans votre orgueil. Imaginez qu\u2019au matin de No\u00ebl vous ouvrez le cadeau d\u2019un ami\n\u2013 et c\u2019est un livre sur les r\u00e9gimes amaigrissants. Vous d\u00e9nouez ensuite un autre\nruban, d\u00e9ballez le cadeau et d\u00e9couvrez, offert par un autre ami, un nouveau\nlivre qui s\u2019intitule <em>Vaincre l\u2019\u00e9go\u00efsme<\/em>. Si vous dites \u00ab&nbsp;merci <em>beaucoup<\/em>&nbsp;\u00bb\n\u00e0 vos amis, vous laissez entendre que \u00ab&nbsp;oui, c\u2019est vrai, je suis gros et\n\u00e9gocentrique&nbsp;\u00bb. Dit autrement, certains cadeaux sont difficiles \u00e0 accepter\nparce qu\u2019en le faisant, on reconna\u00eet avoir des d\u00e9fauts et des faiblesses, et qu\u2019on\na besoin d\u2019aide. Peut-\u00eatre un ami a-t-il r\u00e9alis\u00e9 un jour que vous aviez des difficult\u00e9s\nfinanci\u00e8res et vous a-t-il propos\u00e9 une importante somme d\u2019argent pour vous\naider \u00e0 vous en sortir&nbsp;? Si vous vous \u00eates d\u00e9j\u00e0 trouv\u00e9 dans cette\nsituation, vous avez probablement ressenti une part d\u2019humiliation \u00e0 accepter ce\ndon.<\/p>\n\n\n\n<p>Cette blessure \u00e0 votre orgueil n\u2019est rien en comparaison de\ncelle qui est n\u00e9cessaire pour accepter le cadeau de J\u00e9sus-Christ. No\u00ebl montre\nque nous sommes tellement \u00e9gar\u00e9s, tellement incapables de nous sauver\nnous-m\u00eames qu\u2019il n\u2019y a que la mort du Fils de Dieu lui-m\u00eame pour nous sauver.\nCela d\u00e9montre que vous n\u2019\u00eates <em>pas<\/em> quelqu\u2019un capable de se reprendre pour\nmener une vie meilleure et plus morale.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><em>Comment accepter le vrai cadeau de No\u00ebl ?<\/em><\/h3>\n\n\n\n<p>Pour accepter le vrai cadeau de No\u00ebl, vous devez reconna\u00eetre\nque vous \u00eates un p\u00e9cheur. Vous avez besoin d\u2019une gr\u00e2ce pour vous sauver. Vous\ndevez abandonner les r\u00eanes de votre vie. Et c\u2019est plus qu\u2019aucun d\u2019entre nous\nn\u2019est pr\u00eat \u00e0 faire. Pourtant, la splendeur de J\u00e9sus-Christ tient \u00e0 ce qu\u2019il\ns\u2019est abaiss\u00e9 pour nous montrer son amour. Votre r\u00e9g\u00e9n\u00e9ration spirituelle et\nvotre splendeur future s\u2019obtiendront en prenant le m\u00eame chemin. Il s\u2019est\nabaiss\u00e9 de la splendeur, et la Bible indique qu\u2019on ne peut se placer dans sa\nlumi\u00e8re que par la repentance. C.S. Lewis l\u2019explique parfaitement. Au sujet de\nl\u2019incarnation, il dit&nbsp;:<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><em>Le pouvoir de l&rsquo;humilit\u00e9<\/em><\/h3>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Nous voyons appara\u00eetre un nouveau principe fondamental \u2013 le pouvoir du Tr\u00e8s Haut, qui l\u2019est litt\u00e9ralement, \u00e0 s\u2019abaisser, le pouvoir du plus grand \u00e0 inclure le moindre [\u2026]. En toutes choses, le grand interp\u00e9n\u00e8tre le petit \u2013 et sa capacit\u00e9 \u00e0 le faire est presque la preuve de sa grandeur. Dans le r\u00e9cit chr\u00e9tien, Dieu [\u2026] s\u2019abaisse\u00a0; plus bas que ses hauteurs d\u2019\u00eatre absolu dans le temps et l\u2019espace, au niveau de l\u2019humanit\u00e9\u00a0; plus bas encore si l\u2019on en croit les embryologistes, jusqu\u2019\u00e0 atteindre dans l\u2019ut\u00e9rus les anciennes formes de vie qui ont pr\u00e9c\u00e9d\u00e9 l\u2019homme\u00a0; aussi profond que les origines et les fondements de la Nature qu\u2019Il a cr\u00e9\u00e9e. Mais il s\u2019abaisse pour s\u2019\u00e9lever \u00e0 nouveau et relever avec lui les ruines du monde [\u2026]. On peut imaginer un plongeur, qui se met d\u2019abord nu puis regarde au loin, et le voil\u00e0 disparu dans une gerbe d\u2019\u00e9cume, qui progresse \u00e0 travers les eaux chaudes et les algues vers les couches froides et sombres, sous une pression croissante, pour atteindre les fonds d\u00e9sertiques, couverts de boue et de vases en d\u00e9composition\u00a0; puis il remonte, vers la couleur et la lumi\u00e8re, les poumons pr\u00eats \u00e0 exploser, et il appara\u00eet \u00e0 la surface \u00e0 nouveau, tenant dans sa main le pr\u00e9cieux objet, encore humide, qu\u2019il \u00e9tait all\u00e9 chercher<a href=\"#_edn6\">]<\/a>.<\/p>\n<cite> <br \/>C.S. Lewis, <em>Les miracles : \u00e9tude pr\u00e9liminaire<\/em>, trad. Jacques Blondel, Paris, S.P.B., 1985, chap. 14, [traduction Cl\u00e9]. <\/cite><\/blockquote>\n\n\n\n<h3 class=\"wp-block-heading\"><em>La v\u00e9rit\u00e9 fondamentale<\/em><\/h3>\n\n\n\n<p>Quand J\u00e9sus mourut sur la croix, il y eut des t\u00e9n\u00e8bres sur\ntout le pays (Matthieu 27.45). La Lumi\u00e8re du monde descendit dans les\nprofondeurs de l\u2019obscurit\u00e9 pour nous appeler \u00e0 la merveilleuse lumi\u00e8re de Dieu\n(1&nbsp;Pierre 2.9). Vous ne pouvez pas appr\u00e9hender les promesses de No\u00ebl tant\nque vous ne reconnaissez pas que vous \u00eates incapable de vous sauver, ni m\u00eame\nvous conna\u00eetre vous-m\u00eame, hormis si la lumi\u00e8re de sa gr\u00e2ce, obtenue sans l\u2019avoir\nm\u00e9rit\u00e9e, \u00e9claire votre vie. C\u2019est l\u00e0 la v\u00e9rit\u00e9 fondamentale, la base sur laquelle\nnous pouvons poursuivre notre exploration du sens oubli\u00e9 de No\u00ebl.<br \/><\/p>\n\n\n\n<div class=\"wp-block-media-text alignwide\" style=\"grid-template-columns:30% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"685\" height=\"1024\" src=\"https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2019\/12\/0122.ip_-685x1024.jpg\" alt=\"\" class=\"wp-image-3362 size-full\" srcset=\"https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2019\/12\/0122.ip_-685x1024.jpg 685w, https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2019\/12\/0122.ip_-201x300.jpg 201w, https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2019\/12\/0122.ip_-140x210.jpg 140w, https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2019\/12\/0122.ip_-768x1148.jpg 768w, https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2019\/12\/0122.ip_-74x110.jpg 74w, https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2019\/12\/0122.ip_-281x420.jpg 281w, https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2019\/12\/0122.ip_-288x430.jpg 288w, https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2019\/12\/0122.ip_.jpg 907w\" sizes=\"auto, (max-width: 685px) 100vw, 685px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"has-medium-font-size\"><a href=\"https:\/\/editionscle.com\/vie-chretienne\/255-noel-cache-9782358431224.html\">D\u00e9couvrez le livre sur notre site ou en librairie<\/a><\/p>\n\n\n\n<p><em>La reproduction de cet article est interdite sur tout support. Copyright <a href=\"https:\/\/timothykeller.com\/\">Tim Keller<\/a> et \u00c9ditions Cl\u00e9<\/em><\/p>\n<\/div><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Notes<\/h3>\n\n\n\n<p><a href=\"#_ednref1\">[i]<\/a>\nRobert Marquand, \u201cV\u00e1clav Havel: Crisis of Human Spirit Demands Spiritual\nReawakening\u201d, <em>Christian Science Monitor<\/em>, 22 d\u00e9cembre 2011,\nwww.csmonitor.com\/layout\/set\/print\/world\/europe\/2011\/1223\/vaclav-havel-crisis-of-human-spirit-demands-spiritual-reawakening\nconsult\u00e9 le 29\/08\/2017.<\/p>\n\n\n\n<p><a href=\"#_ednref2\">[ii]<\/a>\nStanford University News Service, \u201cCzech President V\u00e1clav Havel\u2019s Visit to\nStanford\u201d (communiqu\u00e9 de presse), 4 octobre 1994,\nweb.stanford.edu\/dept\/news\/pr\/94\/941004Arc4108.html consult\u00e9 le 29\/08\/2017.<\/p>\n\n\n\n<p><a href=\"#_ednref3\">[iii]<\/a> Extrait de Bertrand Russell, <em>Mysticism\nand Logic: And other Essays<\/em>, London, Longmans, Green, and Company, 1919, p.\n47-48. L\u2019int\u00e9gralit\u00e9 de l\u2019essai peut \u00eatre t\u00e9l\u00e9charg\u00e9e sur de nombreux\nsites internet.<\/p>\n\n\n\n<p><a href=\"#_ednref4\">[iv]<\/a> Dorothy L. Sayers, \u201cThe Greatest\nDrama Ever Staged\u201d, <em>Creed or Chaos? And Other Essays in Popular Theology <\/em>(London:\nHodder and Stoughton, 1940), p. 6.<\/p>\n\n\n\n<p><a href=\"#_ednref5\">[v]<\/a> J.R.R\nTolkien, \u00ab&nbsp;Le retour du roi&nbsp;\u00bb, <em>Le seigneur des anneaux<\/em>,\nPocket, Collection Pocket Jeunesse, 1993.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity\"\/>\n","protected":false},"excerpt":{"rendered":"<p>Chapitre 1 \u2013 Une lumi\u00e8re s\u2019est lev\u00e9e Le peuple qui marchait dans les t\u00e9n\u00e8bres a vu une grande lumi\u00e8re, sur ceux qui habitaient le pays de l\u2019ombre de la mort une lumi\u00e8re a brill\u00e9. [\u2026] Oui, toute chaussure port\u00e9e dans la bataille et tout habit roul\u00e9 dans le sang seront livr\u00e9s aux flammes pour \u00eatre [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2022,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,72,68],"tags":[48,49],"class_list":["post-2021","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite","category-articles","category-extrait","tag-noel-cache","tag-timothy-keller"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Une lumi\u00e8re s\u2019est lev\u00e9e, par Timothy Keller, extrait de son livre \u00abNo\u00ebl cach\u00e9\u00bb - Blog des \u00c9ditions Cl\u00e9<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogs.editionscle.com\/blogcle\/une-lumiere-sest-levee-par-timothy-keller-extrait-de-son-livre-noel-cache\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Une lumi\u00e8re s\u2019est lev\u00e9e, par Timothy Keller, extrait de son livre \u00abNo\u00ebl cach\u00e9\u00bb - Blog des \u00c9ditions Cl\u00e9\" \/>\n<meta property=\"og:description\" content=\"Chapitre 1 \u2013 Une lumi\u00e8re s\u2019est lev\u00e9e Le peuple qui marchait dans les t\u00e9n\u00e8bres a vu une grande lumi\u00e8re, sur ceux qui habitaient le pays de l\u2019ombre de la mort une lumi\u00e8re a brill\u00e9. [\u2026] Oui, toute chaussure port\u00e9e dans la bataille et tout habit roul\u00e9 dans le sang seront livr\u00e9s aux flammes pour \u00eatre [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogs.editionscle.com\/blogcle\/une-lumiere-sest-levee-par-timothy-keller-extrait-de-son-livre-noel-cache\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog des \u00c9ditions Cl\u00e9\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/editionscle\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-17T09:44:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-17T09:44:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2019\/12\/Noelcache\u0301_image.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1596\" \/>\n\t<meta property=\"og:image:height\" content=\"1017\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"\u00c9ditions Cl\u00e9\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@editionscle\" \/>\n<meta name=\"twitter:site\" content=\"@editionscle\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u00c9ditions Cl\u00e9\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"18 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/une-lumiere-sest-levee-par-timothy-keller-extrait-de-son-livre-noel-cache\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/une-lumiere-sest-levee-par-timothy-keller-extrait-de-son-livre-noel-cache\\\/\"},\"author\":{\"name\":\"\u00c9ditions Cl\u00e9\",\"@id\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/#\\\/schema\\\/person\\\/6f614e2cdd8aac468261bff8219ca7a0\"},\"headline\":\"Une lumi\u00e8re s\u2019est lev\u00e9e, par Timothy Keller, extrait de son livre \u00abNo\u00ebl cach\u00e9\u00bb\",\"datePublished\":\"2025-12-17T09:44:34+00:00\",\"dateModified\":\"2025-12-17T09:44:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/une-lumiere-sest-levee-par-timothy-keller-extrait-de-son-livre-noel-cache\\\/\"},\"wordCount\":4510,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/une-lumiere-sest-levee-par-timothy-keller-extrait-de-son-livre-noel-cache\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/12\\\/Noelcache\u0301_image.jpg\",\"keywords\":[\"No\u00ebl cach\u00e9\",\"Timothy Keller\"],\"articleSection\":[\"Actualit\u00e9\",\"Articles\",\"Extrait\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/une-lumiere-sest-levee-par-timothy-keller-extrait-de-son-livre-noel-cache\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/une-lumiere-sest-levee-par-timothy-keller-extrait-de-son-livre-noel-cache\\\/\",\"url\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/une-lumiere-sest-levee-par-timothy-keller-extrait-de-son-livre-noel-cache\\\/\",\"name\":\"Une lumi\u00e8re s\u2019est lev\u00e9e, par Timothy Keller, extrait de son livre \u00abNo\u00ebl cach\u00e9\u00bb - Blog des \u00c9ditions Cl\u00e9\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/une-lumiere-sest-levee-par-timothy-keller-extrait-de-son-livre-noel-cache\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/une-lumiere-sest-levee-par-timothy-keller-extrait-de-son-livre-noel-cache\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/12\\\/Noelcache\u0301_image.jpg\",\"datePublished\":\"2025-12-17T09:44:34+00:00\",\"dateModified\":\"2025-12-17T09:44:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/une-lumiere-sest-levee-par-timothy-keller-extrait-de-son-livre-noel-cache\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/une-lumiere-sest-levee-par-timothy-keller-extrait-de-son-livre-noel-cache\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/une-lumiere-sest-levee-par-timothy-keller-extrait-de-son-livre-noel-cache\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/12\\\/Noelcache\u0301_image.jpg\",\"contentUrl\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/12\\\/Noelcache\u0301_image.jpg\",\"width\":1596,\"height\":1017},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/une-lumiere-sest-levee-par-timothy-keller-extrait-de-son-livre-noel-cache\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Une lumi\u00e8re s\u2019est lev\u00e9e, par Timothy Keller, extrait de son livre \u00abNo\u00ebl cach\u00e9\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/#website\",\"url\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/\",\"name\":\"Blog des \u00c9ditions Cl\u00e9\",\"description\":\"Livres et logiciels pour comprendre la Bible\",\"publisher\":{\"@id\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/#organization\",\"name\":\"Editions Cl\u00e9\",\"url\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/03\\\/Profil_facebookcle.png\",\"contentUrl\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/03\\\/Profil_facebookcle.png\",\"width\":375,\"height\":375,\"caption\":\"Editions Cl\u00e9\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/editionscle\",\"https:\\\/\\\/x.com\\\/editionscle\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/EditionsCle\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/#\\\/schema\\\/person\\\/6f614e2cdd8aac468261bff8219ca7a0\",\"name\":\"\u00c9ditions Cl\u00e9\",\"description\":\"\u00c9ditions Cl\u00e9\",\"sameAs\":[\"https:\\\/\\\/editionscle.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Une lumi\u00e8re s\u2019est lev\u00e9e, par Timothy Keller, extrait de son livre \u00abNo\u00ebl cach\u00e9\u00bb - Blog des \u00c9ditions Cl\u00e9","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogs.editionscle.com\/blogcle\/une-lumiere-sest-levee-par-timothy-keller-extrait-de-son-livre-noel-cache\/","og_locale":"fr_FR","og_type":"article","og_title":"Une lumi\u00e8re s\u2019est lev\u00e9e, par Timothy Keller, extrait de son livre \u00abNo\u00ebl cach\u00e9\u00bb - Blog des \u00c9ditions Cl\u00e9","og_description":"Chapitre 1 \u2013 Une lumi\u00e8re s\u2019est lev\u00e9e Le peuple qui marchait dans les t\u00e9n\u00e8bres a vu une grande lumi\u00e8re, sur ceux qui habitaient le pays de l\u2019ombre de la mort une lumi\u00e8re a brill\u00e9. [\u2026] Oui, toute chaussure port\u00e9e dans la bataille et tout habit roul\u00e9 dans le sang seront livr\u00e9s aux flammes pour \u00eatre [&hellip;]","og_url":"https:\/\/blogs.editionscle.com\/blogcle\/une-lumiere-sest-levee-par-timothy-keller-extrait-de-son-livre-noel-cache\/","og_site_name":"Blog des \u00c9ditions Cl\u00e9","article_publisher":"https:\/\/www.facebook.com\/editionscle","article_published_time":"2025-12-17T09:44:34+00:00","article_modified_time":"2025-12-17T09:44:35+00:00","og_image":[{"width":1596,"height":1017,"url":"https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2019\/12\/Noelcache\u0301_image.jpg","type":"image\/jpeg"}],"author":"\u00c9ditions Cl\u00e9","twitter_card":"summary_large_image","twitter_creator":"@editionscle","twitter_site":"@editionscle","twitter_misc":{"\u00c9crit par":"\u00c9ditions Cl\u00e9","Dur\u00e9e de lecture estim\u00e9e":"18 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blogs.editionscle.com\/blogcle\/une-lumiere-sest-levee-par-timothy-keller-extrait-de-son-livre-noel-cache\/#article","isPartOf":{"@id":"https:\/\/blogs.editionscle.com\/blogcle\/une-lumiere-sest-levee-par-timothy-keller-extrait-de-son-livre-noel-cache\/"},"author":{"name":"\u00c9ditions Cl\u00e9","@id":"https:\/\/blogs.editionscle.com\/blogcle\/#\/schema\/person\/6f614e2cdd8aac468261bff8219ca7a0"},"headline":"Une lumi\u00e8re s\u2019est lev\u00e9e, par Timothy Keller, extrait de son livre \u00abNo\u00ebl cach\u00e9\u00bb","datePublished":"2025-12-17T09:44:34+00:00","dateModified":"2025-12-17T09:44:35+00:00","mainEntityOfPage":{"@id":"https:\/\/blogs.editionscle.com\/blogcle\/une-lumiere-sest-levee-par-timothy-keller-extrait-de-son-livre-noel-cache\/"},"wordCount":4510,"commentCount":0,"publisher":{"@id":"https:\/\/blogs.editionscle.com\/blogcle\/#organization"},"image":{"@id":"https:\/\/blogs.editionscle.com\/blogcle\/une-lumiere-sest-levee-par-timothy-keller-extrait-de-son-livre-noel-cache\/#primaryimage"},"thumbnailUrl":"https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2019\/12\/Noelcache\u0301_image.jpg","keywords":["No\u00ebl cach\u00e9","Timothy Keller"],"articleSection":["Actualit\u00e9","Articles","Extrait"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blogs.editionscle.com\/blogcle\/une-lumiere-sest-levee-par-timothy-keller-extrait-de-son-livre-noel-cache\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blogs.editionscle.com\/blogcle\/une-lumiere-sest-levee-par-timothy-keller-extrait-de-son-livre-noel-cache\/","url":"https:\/\/blogs.editionscle.com\/blogcle\/une-lumiere-sest-levee-par-timothy-keller-extrait-de-son-livre-noel-cache\/","name":"Une lumi\u00e8re s\u2019est lev\u00e9e, par Timothy Keller, extrait de son livre \u00abNo\u00ebl cach\u00e9\u00bb - Blog des \u00c9ditions Cl\u00e9","isPartOf":{"@id":"https:\/\/blogs.editionscle.com\/blogcle\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blogs.editionscle.com\/blogcle\/une-lumiere-sest-levee-par-timothy-keller-extrait-de-son-livre-noel-cache\/#primaryimage"},"image":{"@id":"https:\/\/blogs.editionscle.com\/blogcle\/une-lumiere-sest-levee-par-timothy-keller-extrait-de-son-livre-noel-cache\/#primaryimage"},"thumbnailUrl":"https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2019\/12\/Noelcache\u0301_image.jpg","datePublished":"2025-12-17T09:44:34+00:00","dateModified":"2025-12-17T09:44:35+00:00","breadcrumb":{"@id":"https:\/\/blogs.editionscle.com\/blogcle\/une-lumiere-sest-levee-par-timothy-keller-extrait-de-son-livre-noel-cache\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blogs.editionscle.com\/blogcle\/une-lumiere-sest-levee-par-timothy-keller-extrait-de-son-livre-noel-cache\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blogs.editionscle.com\/blogcle\/une-lumiere-sest-levee-par-timothy-keller-extrait-de-son-livre-noel-cache\/#primaryimage","url":"https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2019\/12\/Noelcache\u0301_image.jpg","contentUrl":"https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2019\/12\/Noelcache\u0301_image.jpg","width":1596,"height":1017},{"@type":"BreadcrumbList","@id":"https:\/\/blogs.editionscle.com\/blogcle\/une-lumiere-sest-levee-par-timothy-keller-extrait-de-son-livre-noel-cache\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/blogs.editionscle.com\/blogcle\/"},{"@type":"ListItem","position":2,"name":"Une lumi\u00e8re s\u2019est lev\u00e9e, par Timothy Keller, extrait de son livre \u00abNo\u00ebl cach\u00e9\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/blogs.editionscle.com\/blogcle\/#website","url":"https:\/\/blogs.editionscle.com\/blogcle\/","name":"Blog des \u00c9ditions Cl\u00e9","description":"Livres et logiciels pour comprendre la Bible","publisher":{"@id":"https:\/\/blogs.editionscle.com\/blogcle\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogs.editionscle.com\/blogcle\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/blogs.editionscle.com\/blogcle\/#organization","name":"Editions Cl\u00e9","url":"https:\/\/blogs.editionscle.com\/blogcle\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blogs.editionscle.com\/blogcle\/#\/schema\/logo\/image\/","url":"https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2018\/03\/Profil_facebookcle.png","contentUrl":"https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2018\/03\/Profil_facebookcle.png","width":375,"height":375,"caption":"Editions Cl\u00e9"},"image":{"@id":"https:\/\/blogs.editionscle.com\/blogcle\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/editionscle","https:\/\/x.com\/editionscle","https:\/\/www.youtube.com\/user\/EditionsCle"]},{"@type":"Person","@id":"https:\/\/blogs.editionscle.com\/blogcle\/#\/schema\/person\/6f614e2cdd8aac468261bff8219ca7a0","name":"\u00c9ditions Cl\u00e9","description":"\u00c9ditions Cl\u00e9","sameAs":["https:\/\/editionscle.com"]}]}},"_links":{"self":[{"href":"https:\/\/blogs.editionscle.com\/blogcle\/wp-json\/wp\/v2\/posts\/2021","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.editionscle.com\/blogcle\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.editionscle.com\/blogcle\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.editionscle.com\/blogcle\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.editionscle.com\/blogcle\/wp-json\/wp\/v2\/comments?post=2021"}],"version-history":[{"count":9,"href":"https:\/\/blogs.editionscle.com\/blogcle\/wp-json\/wp\/v2\/posts\/2021\/revisions"}],"predecessor-version":[{"id":3364,"href":"https:\/\/blogs.editionscle.com\/blogcle\/wp-json\/wp\/v2\/posts\/2021\/revisions\/3364"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.editionscle.com\/blogcle\/wp-json\/wp\/v2\/media\/2022"}],"wp:attachment":[{"href":"https:\/\/blogs.editionscle.com\/blogcle\/wp-json\/wp\/v2\/media?parent=2021"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.editionscle.com\/blogcle\/wp-json\/wp\/v2\/categories?post=2021"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.editionscle.com\/blogcle\/wp-json\/wp\/v2\/tags?post=2021"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}