{"id":2868,"date":"2023-02-17T16:43:06","date_gmt":"2023-02-17T15:43:06","guid":{"rendered":"https:\/\/blogs.editionscle.com\/blogcle\/?p=2868"},"modified":"2023-02-17T18:59:04","modified_gmt":"2023-02-17T17:59:04","slug":"les-etapes-vers-la-maturite-par-jamel-attar","status":"publish","type":"post","link":"https:\/\/blogs.editionscle.com\/blogcle\/les-etapes-vers-la-maturite-par-jamel-attar\/","title":{"rendered":"Les \u00e9tapes vers la maturit\u00e9 chr\u00e9tienne par Jamel ATTAR (1\/2)"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"984\" height=\"248\" src=\"https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2023\/02\/frise-lcm-2.jpg\" alt=\"\" class=\"wp-image-2880\" srcset=\"https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2023\/02\/frise-lcm-2.jpg 984w, https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2023\/02\/frise-lcm-2-300x76.jpg 300w, https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2023\/02\/frise-lcm-2-768x194.jpg 768w, https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2023\/02\/frise-lcm-2-110x28.jpg 110w, https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2023\/02\/frise-lcm-2-420x106.jpg 420w, https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2023\/02\/frise-lcm-2-770x194.jpg 770w\" sizes=\"auto, (max-width: 984px) 100vw, 984px\" \/><figcaption class=\"wp-element-caption\">Le chr\u00e9tien mature (dessin de Nouvelle Cr\u00e9ation)<\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Nous reproduisons ici un extrait du livre<a href=\"https:\/\/editionscle.com\/%C3%A0-para%C3%AEtre\/342-le-chr%C3%A9tien-mature-9782358431613.html\"> <em>Le chr\u00e9tien mature<\/em><\/a> de <a href=\"https:\/\/www.tresorsonore.com\/orateurs\/attar-jamel\">Jamel Attar<\/a> publi\u00e9 aux <a href=\"http:\/\/editionscle.com\">\u00c9ditions Cl\u00e9<\/a>.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Les diff\u00e9rents stades de la vie chr\u00e9tienne&nbsp;<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Avant de commencer l\u2019examen de chaque trait du portrait, il importe d\u2019abord de nous arr\u00eater sur les diff\u00e9rents stades de la vie chr\u00e9tienne avant de parvenir \u00e0 la maturit\u00e9. Ainsi chacun pourra se rendre compte o\u00f9 il en est sur le chemin vers la maturit\u00e9. Car il est fondamental de savoir o\u00f9 l\u2019on se trouve si l\u2019on veut faire les pas n\u00e9cessaires de la croissance et devenir ce chr\u00e9tien mature. Bien s\u00fbr, nous sommes tous conscients qu\u2019un chr\u00e9tien n\u2019atteint pas la maturit\u00e9 d\u00e8s le d\u00e9but de sa vie chr\u00e9tienne. Mais chacun de nous passe par des \u00e9tapes progressives \u00e0 partir de la conversion avant de parvenir au dernier stade.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Et c\u2019est gr\u00e2ce \u00e0 l\u2019ap\u00f4tre Jean d\u2019abord que nous allons d\u00e9couvrir ces \u00e9tapes. Voici ce qu\u2019il \u00e9crit dans sa premi\u00e8re lettre&nbsp;:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><sup>12<\/sup>&nbsp;Je vous \u00e9cris, petits enfants, parce que vos p\u00e9ch\u00e9s vous sont pardonn\u00e9s \u00e0 cause de son nom. <sup>13<\/sup>&nbsp;Je vous \u00e9cris, p\u00e8res, parce que vous connaissez celui qui est d\u00e8s le commencement. Je vous \u00e9cris, jeunes gens, parce que vous avez vaincu le mauvais. Je vous ai \u00e9crit, petits enfants, parce que vous connaissez le P\u00e8re. <sup>14<\/sup>&nbsp;Je vous ai \u00e9crit, p\u00e8res, parce que vous connaissez celui qui est d\u00e8s le commencement. Je vous ai \u00e9crit, jeunes gens, parce que vous \u00eates forts, que la parole de Dieu demeure en vous et que vous avez vaincu le mauvais.<\/p>\n<cite><strong>1 Jean 2.12-14<\/strong><\/cite><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Dans ces trois versets, l\u2019ap\u00f4tre s\u2019adresse \u00e0 trois cat\u00e9gories de personnes&nbsp;: des petits enfants, des jeunes gens et des p\u00e8res. Et il le fait deux fois&nbsp;! Bien s\u00fbr, nous comprenons, d\u2019apr\u00e8s ce qu\u2019il leur dit, qu\u2019il ne parle pas de l\u2019\u00e2ge physique de ces personnes, mais qu\u2019il interpelle ces chr\u00e9tiens d\u2019apr\u00e8s leur maturit\u00e9 spirituelle. C\u2019est dans ce sens que John Stott comprend ces versets. Il pr\u00e9cise en effet que \u00ab&nbsp;les petits-enfants sont ces nouveau-n\u00e9s en Christ. Les jeunes gens sont les chr\u00e9tiens plus d\u00e9velopp\u00e9s, forts et victorieux dans le combat spirituel&nbsp;; tandis que les p\u00e8res poss\u00e8dent la profondeur et la stabilit\u00e9 du chr\u00e9tien d\u2019exp\u00e9rience m\u00fbre&nbsp;\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ces trois groupes de personnes repr\u00e9sentent donc trois \u00e9tapes du d\u00e9veloppement spirituel. La famille de Dieu se compose en effet de membres de tous \u00e2ges, c\u2019est-\u00e0-dire de membres de maturit\u00e9 spirituelle diff\u00e9rente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Examinons chacun de ces trois \u00e2ges en retenant bien que chaque \u00e2ge est d\u00e9terminant pour atteindre la maturit\u00e9, puisque nous passons tous obligatoirement par chacune de ces \u00e9tapes afin de parvenir \u00e0 la derni\u00e8re.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Les petits enfants = les d\u00e9buts de la vie chr\u00e9tienne<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La vie chr\u00e9tienne commence par le pardon des p\u00e9ch\u00e9s. Voil\u00e0 pourquoi l\u2019ap\u00f4tre Jean, en s\u2019adressant aux petits enfants, leur dit au verset&nbsp;12&nbsp;: \u00ab&nbsp;vos p\u00e9ch\u00e9s vous sont pardonn\u00e9s \u00e0 cause de son nom&nbsp;\u00bb. Leurs p\u00e9ch\u00e9s sont pardonn\u00e9s, parce que J\u00e9sus-Christ a donn\u00e9 sa vie pour eux, il a pris leurs p\u00e9ch\u00e9s sur lui. Ces croyants ont confess\u00e9 le nom de J\u00e9sus pour \u00eatre sauv\u00e9s, ils ont fait appel au nom du Seigneur, reconnaissant en lui celui qui pardonne&nbsp;: \u00ab&nbsp;Seigneur J\u00e9sus, sauve-moi&nbsp;!&nbsp;\u00bb En recevant le pardon, ils sont d\u00e9sormais entr\u00e9s dans une nouvelle relation avec Dieu, qui est ainsi devenu leur P\u00e8re&nbsp;: \u00ab&nbsp;Je vous ai \u00e9crit, petits enfants, parce que vous connaissez le P\u00e8re&nbsp;\u00bb (v.&nbsp;13). Ils sont donc n\u00e9s de nouveau et font partie de la famille de Dieu (\u00c9ph\u00e9siens 2.19)&nbsp;; Dieu a envoy\u00e9 dans leur c\u0153ur l\u2019Esprit saint, qui fait jaillir de leur c\u0153ur ce cri&nbsp;: \u00ab&nbsp;Abba&nbsp;! P\u00e8re&nbsp;!&nbsp;\u00bb (Galates 4.6). Cette premi\u00e8re \u00e9tape est pleine d\u2019\u00e9merveillement&nbsp;! Les petits enfants qui viennent au monde sont fascin\u00e9s par tout ce qui les entoure, car ils le d\u00e9couvrent petit \u00e0 petit. Ainsi, les nouveau-n\u00e9s qui entrent dans le royaume de Dieu s\u2019\u00e9bahissent de tant de splendeurs, propres au monde de Dieu. Leur c\u0153ur est gonfl\u00e9 de l\u2019amour de leur Seigneur&nbsp;; leur joie est toute charmante de spontan\u00e9it\u00e9 et de candeur&nbsp;; leur soif de Dieu est insatiable.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tout cela ne doit pas dispara\u00eetre ou \u00eatre abandonn\u00e9, mais doit plut\u00f4t \u00eatre acquis et constituer le socle sur lequel construire, par lequel se d\u00e9velopper. Car aussi charmante soit cette \u00e9tape, la vie chr\u00e9tienne ne doit pas s\u2019y figer.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Les jeunes gens = les chr\u00e9tiens en chemin vers la maturit\u00e9<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">En effet, les petits enfants ne doivent pas le rester, mais progresser sur le chemin de la foi pour devenir des jeunes gens, c\u2019est-\u00e0-dire des chr\u00e9tiens en chemin vers la maturit\u00e9. Ainsi l\u2019ap\u00f4tre de Christ s\u2019adresse \u00e0 ce deuxi\u00e8me groupe de chr\u00e9tiens, au verset&nbsp;13&nbsp;: \u00ab&nbsp;Je vous \u00e9cris, jeunes gens, parce que vous avez vaincu le mauvais&nbsp;\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ces jeunes gens ne sont pas seulement d\u00e9livr\u00e9s de la peine du p\u00e9ch\u00e9, mais aussi de la puissance du p\u00e9ch\u00e9. Ils savent assur\u00e9ment que leurs p\u00e9ch\u00e9s leur ont \u00e9t\u00e9 pardonn\u00e9s&nbsp;; ils sont maintenant au stade du triomphe sur le p\u00e9ch\u00e9. En langage doctrinal, ces croyants n\u2019en sont plus au stade de la justification par la foi, mais de la sanctification. Ils sont entr\u00e9s en lutte contre le mal et ne se laissent plus dominer par lui. Parce que leur foi a grandi, ils ne se contentent pas de croire que Christ est mort pour leurs p\u00e9ch\u00e9s, ils savent aussi que J\u00e9sus a vaincu le p\u00e9ch\u00e9 pour eux. Par lui, ils sont vainqueurs. Et pourquoi ont-ils vaincu le malin&nbsp;? Parce qu\u2019ils sont forts&nbsp;: \u00ab&nbsp;Je vous ai \u00e9crit, jeunes gens, parce que vous \u00eates forts, que la parole de Dieu demeure en vous et que vous avez vaincu le mauvais&nbsp;\u00bb (v.&nbsp;14). Ce n\u2019est pas que leur force leur vienne d\u2019eux-m\u00eames&nbsp;; ils sont forts parce que le Christ les fortifie, c\u2019est la Parole de Dieu qui demeure en eux qui leur communique puissance et victoire. Elle est l\u2019\u00e9p\u00e9e de l\u2019Esprit saint par laquelle ils se d\u00e9fendent contre les assauts du mauvais. Les chr\u00e9tiens qui sont donc \u00e0 cette deuxi\u00e8me \u00e9tape de leur d\u00e9veloppement spirituel savent recourir \u00e0 la Parole, comme le Seigneur J\u00e9sus, lorsqu\u2019ils sont tent\u00e9s par l\u2019ennemi. \u00c0 l\u2019exemple du Seigneur qui r\u00e9pondait aux suggestions de Satan par des citations de la Parole de Dieu, eux aussi se d\u00e9fendent en s\u2019appuyant sur la Parole de Dieu. Cette capacit\u00e9 est acquise par une fr\u00e9quentation assidue de la Parole qui est rumin\u00e9e, m\u00e9dit\u00e9e et assimil\u00e9e pour devenir ce qui oriente les choix de vie et forme la vision du monde. Cette Parole demeure en eux, dans le sens o\u00f9 ils l\u2019ont int\u00e9gr\u00e9e pour qu\u2019elle renouvelle leur intelligence, et les ouvre sur la r\u00e9alit\u00e9 de l\u2019Esprit saint. Elle fait partie d\u2019eux&nbsp;;&nbsp;elle est vivante en eux. Vous voyez, c\u2019est lorsque la Parole de Dieu demeure en nous et nous aide \u00e0 dire non aux tentations, que nous sommes vraiment en route vers la maturit\u00e9. Rappelons-nous cette parole du Seigneur&nbsp;: \u00ab&nbsp;Comment le jeune homme rendra-t-il pur son sentier&nbsp;? En se conformant \u00e0 ta parole&nbsp;\u00bb (Psaumes 119.9).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Les p\u00e8res = les chr\u00e9tiens matures<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Les enfants \u00e9voquent les d\u00e9buts de la vie chr\u00e9tienne, les jeunes gens symbolisent tous les chr\u00e9tiens en chemin vers la maturit\u00e9\u2026 Et les p\u00e8res alors&nbsp;? Bien s\u00fbr, les p\u00e8res, ce sont les chr\u00e9tiens matures. Ils sont la derni\u00e8re \u00e9tape du d\u00e9veloppement normal de la vie chr\u00e9tienne&nbsp;: ils repr\u00e9sentent l\u2019\u00e2ge de la maturit\u00e9 et de la stabilit\u00e9 dans la foi. Il est \u00e9vident que ce stade s\u2019enrichit des \u00e9tapes pr\u00e9c\u00e9dentes. Et vu tout ce qu\u2019offre la deuxi\u00e8me \u00e9tape, nous pourrions nous dire&nbsp;: \u00ab&nbsp;N\u2019est-ce pas d\u00e9j\u00e0 fabuleux&nbsp;? Pardon des p\u00e9ch\u00e9s, connaissance du P\u00e8re comme celui qui nous a engendr\u00e9s \u00e0 une vie nouvelle, triomphe du mal et de Satan, enracinement dans la Parole de Dieu, marche et vie \u00e0 la lumi\u00e8re de la Parole\u2026&nbsp;\u00bb. Mais que manque-t-il \u00e0 ces jeunes gens pour \u00eatre des adultes ou \u00eatre matures dans la foi&nbsp;? Quelle chose suppl\u00e9mentaire leur faudrait-il pour avoir ce qu\u2019ils n\u2019ont pas encore&nbsp;? Lisons le verset&nbsp;12 pour avoir la r\u00e9ponse&nbsp;: \u00ab&nbsp;Je vous \u00e9cris, p\u00e8res, parce que vous connaissez celui qui est d\u00e8s le commencement&nbsp;\u00bb. Quand il s\u2019adresse pour la deuxi\u00e8me fois aux petits enfants et aux jeunes gens, Jean ajoute de nouveaux \u00e9l\u00e9ments, comme pour signifier justement le besoin de d\u00e9veloppement. Mais, en s\u2019adressant aux p\u00e8res, Jean r\u00e9p\u00e8te exactement les m\u00eames paroles qu\u2019au verset&nbsp;14&nbsp;: \u00ab&nbsp;Je vous ai \u00e9crit, p\u00e8res, parce que vous connaissez celui qui est d\u00e8s le commencement&nbsp;\u00bb. Seul change le temps du premier verbe. Par ces mots, Jean nous renvoie vers les premi\u00e8res lignes de sa lettre&nbsp;:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Ce qui \u00e9tait d\u00e8s le commencement, ce que nous avons entendu, ce que nous avons vu de nos yeux, ce que nous avons contempl\u00e9 et que nos mains ont touch\u00e9 concernant la parole de la vie, nous vous l\u2019annon\u00e7ons.<\/p>\n<cite><strong>1 Jean 1.1<\/strong><\/cite><\/blockquote>\n\n\n\n<h3 class=\"wp-block-heading\">Trois ann\u00e9es pass\u00e9es avec J\u00e9sus<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Dans ce verset, Jean nous parle des trois ann\u00e9es qu\u2019il a pass\u00e9es, lui et les autres disciples, aupr\u00e8s de J\u00e9sus. Ils ont march\u00e9 avec lui, ils l\u2019ont entendu, ils l\u2019ont vu, ils l\u2019ont contempl\u00e9 et touch\u00e9 de leurs mains. N\u2019allons pas croire que l\u2019ap\u00f4tre nous parle seulement de proximit\u00e9 physique&nbsp;; non, dans ce d\u00e9but de sa lettre, Jean \u00e9voque surtout la proximit\u00e9 et l\u2019intimit\u00e9 spirituelles que les disciples avaient avec le Seigneur. Leurs oreilles ont entendu des paroles ineffables&nbsp;; leurs yeux ont vu la gloire du Fils de Dieu&nbsp;; ils ont touch\u00e9 non un corps humain, mais le corps dans lequel habite toute la pl\u00e9nitude de la divinit\u00e9 (Colossiens 2.9). Jean a repos\u00e9 sa t\u00eate sur le sein de J\u00e9sus, le Fils de Dieu, qui \u00e9tait dans le sein du P\u00e8re (Jean 1.18&nbsp;\u2013&nbsp;NEG). Il s\u2019agit donc de communion avec le P\u00e8re et avec le Fils par l\u2019Esprit saint. Il ne s\u2019agit pas seulement d\u2019un homme, J\u00e9sus, mais de celui qui \u00e9tait d\u00e8s le commencement. Ainsi, c\u2019est avec le divin, avec le Seigneur, avec le glorieux, avec la vie m\u00eame qu\u2019ils \u00e9taient en communion. Ils le connaissaient dans sa personne.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Devenir comme lui<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c0 force d\u2019\u00eatre avec lui, les ap\u00f4tres sont devenus comme lui. C\u2019est l\u2019\u00e9tape supr\u00eame, ce pour quoi Dieu \u0153uvre dans notre vie&nbsp;; c\u2019est le but et la volont\u00e9 de Dieu pour nous tous que nous soyons comme son Fils, \u00e0 force d\u2019\u00eatre avec lui, car il nous a \u00ab&nbsp;pr\u00e9destin\u00e9s \u00e0 devenir conformes \u00e0 l\u2019image de son Fils, afin que celui-ci soit le premier-n\u00e9 d\u2019un grand nombre de fr\u00e8res&nbsp;\u00bb (Romains 8.29). C\u2019est cela le bien pour lequel Dieu fait travailler toutes les choses.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les p\u00e8res, c\u2019est-\u00e0-dire les chr\u00e9tiens matures, connaissent donc \u00ab&nbsp;celui qui est d\u00e8s le commencement&nbsp;\u00bb, c\u2019est-\u00e0-dire qu\u2019ils connaissent d\u2019une connaissance toute spirituelle, toute intime, toute profonde, le Seigneur J\u00e9sus dans son humanit\u00e9, mais aussi dans son \u00e9ternit\u00e9, dans sa divinit\u00e9. Le chr\u00e9tien mature, c\u2019est celui qui a contempl\u00e9 de ses yeux, ceux du c\u0153ur, et touch\u00e9 de ses mains, celles de la foi. Il ne conna\u00eet pas seulement la force du Seigneur et sa victoire, mais il conna\u00eet sa personne. Le chr\u00e9tien mature a d\u00e9pass\u00e9 le besoin de se sentir fort, chose propre \u00e0 la jeunesse&nbsp;; il l\u2019est de toute fa\u00e7on. Il a d\u00e9pass\u00e9 le besoin de demeurer seulement dans la Parole \u00e9crite&nbsp;; il demeure maintenant aussi dans la Parole vivante, dans le Fils et dans le P\u00e8re. Le chr\u00e9tien mature s\u2019identifie avec le Christ et conna\u00eet la puissance de sa r\u00e9surrection, son triomphe donc sur la mort, sur Satan, sur le mal. Mais, plus encore, il conna\u00eet le Christ parce qu\u2019il partage ses souffrances. Tout ce qui lui importe, c\u2019est l\u2019excellence de la connaissance de Christ&nbsp;:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Ainsi je conna\u00eetrai Christ, la puissance de sa r\u00e9surrection et la communion \u00e0 ses souffrances en devenant conforme \u00e0 lui dans sa mort pour parvenir, d\u2019une mani\u00e8re ou d\u2019une autre, \u00e0 la r\u00e9surrection des morts.<\/p>\n<cite><strong>Philippiens 3.10-11<\/strong><\/cite><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Il est mort, crucifi\u00e9 comme le Christ. Il est crucifi\u00e9 avec le Christ&nbsp;; il vit, mais ce n\u2019est plus lui qui vit, c\u2019est Christ qui vit en lui (Galates 2.20). \u00c0 force d\u2019\u00eatre en sa pr\u00e9sence, il finit par \u00eatre comme lui&nbsp;: \u00ab&nbsp;Nous tous qui, sans voile sur le visage, contemplons comme dans un miroir la gloire du Seigneur, nous sommes transform\u00e9s \u00e0 son image, de gloire en gloire, par l\u2019Esprit du Seigneur&nbsp;\u00bb (2&nbsp;Corinthiens 3.18).<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\">(voir <a href=\"https:\/\/blogs.editionscle.com\/blogcle\/les-etapes-vers-la-maturite-chretienne-par-jamel-attar-2-2\/\">les stades anormaux : le chr\u00e9tien charnel et le chr\u00e9tien r\u00e9trograde dans la partie de 2 de l&rsquo;article<\/a>).<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Tendons vers la maturit\u00e9<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Il y a des v\u00e9rit\u00e9s profondes, difficiles \u00e0 saisir du premier coup et qui demandent donc de l\u2019attention et des efforts. Le but n\u2019est pas de se faire une grosse t\u00eate, mais un c\u0153ur ob\u00e9issant, qui sait faire la diff\u00e9rence entre le bien et le mal. \u00ab&nbsp;Tendons vers la maturit\u00e9&nbsp;\u00bb, c\u2019est-\u00e0-dire vers l\u2019intelligence du sacrifice du Christ, sa place et son r\u00f4le au ciel, sa m\u00e9diation, sa souveraine pr\u00eatrise&nbsp;: c\u2019est l\u2019invitation pressante que Dieu adresse \u00e0 tout chr\u00e9tien. Le d\u00e9but de la vie chr\u00e9tienne se caract\u00e9rise par un enseignement des rudiments de la Parole de Dieu, un enseignement excellent en soi, mais qui doit \u00eatre d\u00e9pass\u00e9. Nous sommes appel\u00e9s \u00e0 d\u00e9passer l\u2019enseignement \u00e9l\u00e9mentaire pour rechercher la nourriture solide qui fera de nous des chr\u00e9tiens matures. Ce dernier stade est le degr\u00e9 normal d\u2019aboutissement de tout chr\u00e9tien qui a un certain nombre d\u2019ann\u00e9es de vie chr\u00e9tienne. Or, ce stade ne peut \u00eatre atteint sans un r\u00e9el approfondissement des v\u00e9rit\u00e9s spirituelles. Malheureusement, la tendance aujourd\u2019hui est \u00e0 la n\u00e9gligence de la connaissance, voire au refus des enseignements approfondis. Cette position ne peut que produire des nains spirituels. \u00ab&nbsp;Surtout pas de doctrine&nbsp;!&nbsp;\u00bb disent certains. Mais affirmer cela, c\u2019est dire que nous n\u2019avons pas besoin d\u2019enseignement. Or, justement, l\u2019auteur lie \u00e9troitement enseignement approfondi et d\u00e9veloppement spirituel ou v\u00e9rit\u00e9s ardues et croissance dans la foi. Il est urgent de voir le lien entre nourriture solide et maturit\u00e9, entre connaissance de Dieu et croissance.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\">Reproduction interdite sans autorisation \u00e9crite des \u00c9ditions Cl\u00e9. Copyright 2023.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\" style=\"grid-template-columns:28% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"719\" height=\"1024\" src=\"https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2023\/02\/0161.ip_-719x1024.jpg\" alt=\"\" class=\"wp-image-2870 size-full\" srcset=\"https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2023\/02\/0161.ip_-719x1024.jpg 719w, https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2023\/02\/0161.ip_-211x300.jpg 211w, https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2023\/02\/0161.ip_-77x110.jpg 77w, https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2023\/02\/0161.ip_-295x420.jpg 295w, https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2023\/02\/0161.ip_-302x430.jpg 302w, https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2023\/02\/0161.ip_.jpg 758w\" sizes=\"auto, (max-width: 719px) 100vw, 719px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"wp-block-paragraph\">D\u00e9couvrez le livre de <a href=\"https:\/\/editionscle.com\/544-jamel-attar\">Jamel Attar<\/a> chez votre libraire ou sur notre <a href=\"https:\/\/editionscle.com\/%C3%A0-para%C3%AEtre\/342-le-chr%C3%A9tien-mature-9782358431613.html\">boutique<\/a><\/p>\n<\/div><\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Entretien avec Jamel ATTAR - \u00abLe Chr\u00e9tien mature\u00bb - Nouveau livre aux \u00c9ditions Cl\u00e9\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/BBNiEM57qBU?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><figcaption class=\"wp-element-caption\">Vid\u00e9o entretien avec Jamel Attar a propos de son livre (10:40)<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Nous reproduisons ici un extrait du livre Le chr\u00e9tien mature de Jamel Attar publi\u00e9 aux \u00c9ditions Cl\u00e9. Les diff\u00e9rents stades de la vie chr\u00e9tienne&nbsp; Avant de commencer l\u2019examen de chaque trait du portrait, il importe d\u2019abord de nous arr\u00eater sur les diff\u00e9rents stades de la vie chr\u00e9tienne avant de parvenir \u00e0 la maturit\u00e9. Ainsi chacun [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2900,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,72,68],"tags":[169,167,172],"class_list":["post-2868","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite","category-articles","category-extrait","tag-attar","tag-jamel-attar","tag-le-chretien-mature"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les \u00e9tapes vers la maturit\u00e9 chr\u00e9tienne par Jamel ATTAR (1\/2) - Blog des \u00c9ditions Cl\u00e9<\/title>\n<meta name=\"description\" content=\"Les diff\u00e9rents stades de la vie chr\u00e9tienne avant de parvenir \u00e0 la maturit\u00e9.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogs.editionscle.com\/blogcle\/les-etapes-vers-la-maturite-par-jamel-attar\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les \u00e9tapes vers la maturit\u00e9 chr\u00e9tienne par Jamel ATTAR (1\/2) - Blog des \u00c9ditions Cl\u00e9\" \/>\n<meta property=\"og:description\" content=\"Les diff\u00e9rents stades de la vie chr\u00e9tienne avant de parvenir \u00e0 la maturit\u00e9.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogs.editionscle.com\/blogcle\/les-etapes-vers-la-maturite-par-jamel-attar\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog des \u00c9ditions Cl\u00e9\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/editionscle\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-17T15:43:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-17T17:59:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2023\/02\/frise-lcm-2-reduite-partie-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"893\" \/>\n\t<meta property=\"og:image:height\" content=\"288\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"\u00c9ditions Cl\u00e9\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@editionscle\" \/>\n<meta name=\"twitter:site\" content=\"@editionscle\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u00c9ditions Cl\u00e9\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"13 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/les-etapes-vers-la-maturite-par-jamel-attar\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/les-etapes-vers-la-maturite-par-jamel-attar\\\/\"},\"author\":{\"name\":\"\u00c9ditions Cl\u00e9\",\"@id\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/#\\\/schema\\\/person\\\/6f614e2cdd8aac468261bff8219ca7a0\"},\"headline\":\"Les \u00e9tapes vers la maturit\u00e9 chr\u00e9tienne par Jamel ATTAR (1\\\/2)\",\"datePublished\":\"2023-02-17T15:43:06+00:00\",\"dateModified\":\"2023-02-17T17:59:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/les-etapes-vers-la-maturite-par-jamel-attar\\\/\"},\"wordCount\":2705,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/les-etapes-vers-la-maturite-par-jamel-attar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/02\\\/frise-lcm-2-reduite-partie-1.jpg\",\"keywords\":[\"Attar\",\"Jamel Attar\",\"le chretien mature\"],\"articleSection\":[\"Actualit\u00e9\",\"Articles\",\"Extrait\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/les-etapes-vers-la-maturite-par-jamel-attar\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/les-etapes-vers-la-maturite-par-jamel-attar\\\/\",\"url\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/les-etapes-vers-la-maturite-par-jamel-attar\\\/\",\"name\":\"Les \u00e9tapes vers la maturit\u00e9 chr\u00e9tienne par Jamel ATTAR (1\\\/2) - Blog des \u00c9ditions Cl\u00e9\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/les-etapes-vers-la-maturite-par-jamel-attar\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/les-etapes-vers-la-maturite-par-jamel-attar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/02\\\/frise-lcm-2-reduite-partie-1.jpg\",\"datePublished\":\"2023-02-17T15:43:06+00:00\",\"dateModified\":\"2023-02-17T17:59:04+00:00\",\"description\":\"Les diff\u00e9rents stades de la vie chr\u00e9tienne avant de parvenir \u00e0 la maturit\u00e9.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/les-etapes-vers-la-maturite-par-jamel-attar\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/les-etapes-vers-la-maturite-par-jamel-attar\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/les-etapes-vers-la-maturite-par-jamel-attar\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/02\\\/frise-lcm-2-reduite-partie-1.jpg\",\"contentUrl\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/02\\\/frise-lcm-2-reduite-partie-1.jpg\",\"width\":893,\"height\":288},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/les-etapes-vers-la-maturite-par-jamel-attar\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les \u00e9tapes vers la maturit\u00e9 chr\u00e9tienne par Jamel ATTAR (1\\\/2)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/#website\",\"url\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/\",\"name\":\"Blog des \u00c9ditions Cl\u00e9\",\"description\":\"Livres et logiciels pour comprendre la Bible\",\"publisher\":{\"@id\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/#organization\",\"name\":\"Editions Cl\u00e9\",\"url\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/03\\\/Profil_facebookcle.png\",\"contentUrl\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/03\\\/Profil_facebookcle.png\",\"width\":375,\"height\":375,\"caption\":\"Editions Cl\u00e9\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/editionscle\",\"https:\\\/\\\/x.com\\\/editionscle\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/EditionsCle\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/#\\\/schema\\\/person\\\/6f614e2cdd8aac468261bff8219ca7a0\",\"name\":\"\u00c9ditions Cl\u00e9\",\"description\":\"\u00c9ditions Cl\u00e9\",\"sameAs\":[\"https:\\\/\\\/editionscle.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les \u00e9tapes vers la maturit\u00e9 chr\u00e9tienne par Jamel ATTAR (1\/2) - Blog des \u00c9ditions Cl\u00e9","description":"Les diff\u00e9rents stades de la vie chr\u00e9tienne avant de parvenir \u00e0 la maturit\u00e9.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogs.editionscle.com\/blogcle\/les-etapes-vers-la-maturite-par-jamel-attar\/","og_locale":"fr_FR","og_type":"article","og_title":"Les \u00e9tapes vers la maturit\u00e9 chr\u00e9tienne par Jamel ATTAR (1\/2) - Blog des \u00c9ditions Cl\u00e9","og_description":"Les diff\u00e9rents stades de la vie chr\u00e9tienne avant de parvenir \u00e0 la maturit\u00e9.","og_url":"https:\/\/blogs.editionscle.com\/blogcle\/les-etapes-vers-la-maturite-par-jamel-attar\/","og_site_name":"Blog des \u00c9ditions Cl\u00e9","article_publisher":"https:\/\/www.facebook.com\/editionscle","article_published_time":"2023-02-17T15:43:06+00:00","article_modified_time":"2023-02-17T17:59:04+00:00","og_image":[{"width":893,"height":288,"url":"https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2023\/02\/frise-lcm-2-reduite-partie-1.jpg","type":"image\/jpeg"}],"author":"\u00c9ditions Cl\u00e9","twitter_card":"summary_large_image","twitter_creator":"@editionscle","twitter_site":"@editionscle","twitter_misc":{"\u00c9crit par":"\u00c9ditions Cl\u00e9","Dur\u00e9e de lecture estim\u00e9e":"13 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blogs.editionscle.com\/blogcle\/les-etapes-vers-la-maturite-par-jamel-attar\/#article","isPartOf":{"@id":"https:\/\/blogs.editionscle.com\/blogcle\/les-etapes-vers-la-maturite-par-jamel-attar\/"},"author":{"name":"\u00c9ditions Cl\u00e9","@id":"https:\/\/blogs.editionscle.com\/blogcle\/#\/schema\/person\/6f614e2cdd8aac468261bff8219ca7a0"},"headline":"Les \u00e9tapes vers la maturit\u00e9 chr\u00e9tienne par Jamel ATTAR (1\/2)","datePublished":"2023-02-17T15:43:06+00:00","dateModified":"2023-02-17T17:59:04+00:00","mainEntityOfPage":{"@id":"https:\/\/blogs.editionscle.com\/blogcle\/les-etapes-vers-la-maturite-par-jamel-attar\/"},"wordCount":2705,"commentCount":0,"publisher":{"@id":"https:\/\/blogs.editionscle.com\/blogcle\/#organization"},"image":{"@id":"https:\/\/blogs.editionscle.com\/blogcle\/les-etapes-vers-la-maturite-par-jamel-attar\/#primaryimage"},"thumbnailUrl":"https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2023\/02\/frise-lcm-2-reduite-partie-1.jpg","keywords":["Attar","Jamel Attar","le chretien mature"],"articleSection":["Actualit\u00e9","Articles","Extrait"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blogs.editionscle.com\/blogcle\/les-etapes-vers-la-maturite-par-jamel-attar\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blogs.editionscle.com\/blogcle\/les-etapes-vers-la-maturite-par-jamel-attar\/","url":"https:\/\/blogs.editionscle.com\/blogcle\/les-etapes-vers-la-maturite-par-jamel-attar\/","name":"Les \u00e9tapes vers la maturit\u00e9 chr\u00e9tienne par Jamel ATTAR (1\/2) - Blog des \u00c9ditions Cl\u00e9","isPartOf":{"@id":"https:\/\/blogs.editionscle.com\/blogcle\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blogs.editionscle.com\/blogcle\/les-etapes-vers-la-maturite-par-jamel-attar\/#primaryimage"},"image":{"@id":"https:\/\/blogs.editionscle.com\/blogcle\/les-etapes-vers-la-maturite-par-jamel-attar\/#primaryimage"},"thumbnailUrl":"https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2023\/02\/frise-lcm-2-reduite-partie-1.jpg","datePublished":"2023-02-17T15:43:06+00:00","dateModified":"2023-02-17T17:59:04+00:00","description":"Les diff\u00e9rents stades de la vie chr\u00e9tienne avant de parvenir \u00e0 la maturit\u00e9.","breadcrumb":{"@id":"https:\/\/blogs.editionscle.com\/blogcle\/les-etapes-vers-la-maturite-par-jamel-attar\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blogs.editionscle.com\/blogcle\/les-etapes-vers-la-maturite-par-jamel-attar\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blogs.editionscle.com\/blogcle\/les-etapes-vers-la-maturite-par-jamel-attar\/#primaryimage","url":"https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2023\/02\/frise-lcm-2-reduite-partie-1.jpg","contentUrl":"https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2023\/02\/frise-lcm-2-reduite-partie-1.jpg","width":893,"height":288},{"@type":"BreadcrumbList","@id":"https:\/\/blogs.editionscle.com\/blogcle\/les-etapes-vers-la-maturite-par-jamel-attar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/blogs.editionscle.com\/blogcle\/"},{"@type":"ListItem","position":2,"name":"Les \u00e9tapes vers la maturit\u00e9 chr\u00e9tienne par Jamel ATTAR (1\/2)"}]},{"@type":"WebSite","@id":"https:\/\/blogs.editionscle.com\/blogcle\/#website","url":"https:\/\/blogs.editionscle.com\/blogcle\/","name":"Blog des \u00c9ditions Cl\u00e9","description":"Livres et logiciels pour comprendre la Bible","publisher":{"@id":"https:\/\/blogs.editionscle.com\/blogcle\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogs.editionscle.com\/blogcle\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/blogs.editionscle.com\/blogcle\/#organization","name":"Editions Cl\u00e9","url":"https:\/\/blogs.editionscle.com\/blogcle\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blogs.editionscle.com\/blogcle\/#\/schema\/logo\/image\/","url":"https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2018\/03\/Profil_facebookcle.png","contentUrl":"https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2018\/03\/Profil_facebookcle.png","width":375,"height":375,"caption":"Editions Cl\u00e9"},"image":{"@id":"https:\/\/blogs.editionscle.com\/blogcle\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/editionscle","https:\/\/x.com\/editionscle","https:\/\/www.youtube.com\/user\/EditionsCle"]},{"@type":"Person","@id":"https:\/\/blogs.editionscle.com\/blogcle\/#\/schema\/person\/6f614e2cdd8aac468261bff8219ca7a0","name":"\u00c9ditions Cl\u00e9","description":"\u00c9ditions Cl\u00e9","sameAs":["https:\/\/editionscle.com"]}]}},"_links":{"self":[{"href":"https:\/\/blogs.editionscle.com\/blogcle\/wp-json\/wp\/v2\/posts\/2868","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.editionscle.com\/blogcle\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.editionscle.com\/blogcle\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.editionscle.com\/blogcle\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.editionscle.com\/blogcle\/wp-json\/wp\/v2\/comments?post=2868"}],"version-history":[{"count":10,"href":"https:\/\/blogs.editionscle.com\/blogcle\/wp-json\/wp\/v2\/posts\/2868\/revisions"}],"predecessor-version":[{"id":2898,"href":"https:\/\/blogs.editionscle.com\/blogcle\/wp-json\/wp\/v2\/posts\/2868\/revisions\/2898"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.editionscle.com\/blogcle\/wp-json\/wp\/v2\/media\/2900"}],"wp:attachment":[{"href":"https:\/\/blogs.editionscle.com\/blogcle\/wp-json\/wp\/v2\/media?parent=2868"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.editionscle.com\/blogcle\/wp-json\/wp\/v2\/categories?post=2868"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.editionscle.com\/blogcle\/wp-json\/wp\/v2\/tags?post=2868"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}