{"id":2893,"date":"2023-02-17T18:49:08","date_gmt":"2023-02-17T17:49:08","guid":{"rendered":"https:\/\/blogs.editionscle.com\/blogcle\/?p=2893"},"modified":"2023-02-17T19:00:38","modified_gmt":"2023-02-17T18:00:38","slug":"les-etapes-vers-la-maturite-chretienne-par-jamel-attar-2-2","status":"publish","type":"post","link":"https:\/\/blogs.editionscle.com\/blogcle\/les-etapes-vers-la-maturite-chretienne-par-jamel-attar-2-2\/","title":{"rendered":"Les \u00e9tapes vers la maturit\u00e9 chr\u00e9tienne par Jamel ATTAR (2\/2)"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"984\" height=\"248\" src=\"https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2023\/02\/frise-lcm-2.jpg\" alt=\"\" class=\"wp-image-2880\" srcset=\"https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2023\/02\/frise-lcm-2.jpg 984w, https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2023\/02\/frise-lcm-2-300x76.jpg 300w, https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2023\/02\/frise-lcm-2-768x194.jpg 768w, https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2023\/02\/frise-lcm-2-110x28.jpg 110w, https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2023\/02\/frise-lcm-2-420x106.jpg 420w, https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2023\/02\/frise-lcm-2-770x194.jpg 770w\" sizes=\"auto, (max-width: 984px) 100vw, 984px\" \/><figcaption class=\"wp-element-caption\">Le chr\u00e9tien mature (dessin de Nouvelle Cr\u00e9ation)<\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Nous reproduisons ici la suite de et fin de l&rsquo;extrait du livre<a href=\"https:\/\/editionscle.com\/%C3%A0-para%C3%AEtre\/342-le-chr%C3%A9tien-mature-9782358431613.html\"> <em>Le chr\u00e9tien mature<\/em><\/a> de <a href=\"https:\/\/www.tresorsonore.com\/orateurs\/attar-jamel\">Jamel Attar<\/a> publi\u00e9 aux <a href=\"http:\/\/editionscle.com\">\u00c9ditions Cl\u00e9<\/a>.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Les stades anormaux de la vie chr\u00e9tienne&nbsp;<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/blogs.editionscle.com\/blogcle\/les-etapes-vers-la-maturite-par-jamel-attar\/\">Voir la partie 1 de l&rsquo;article pour les 3 degr\u00e9s normaux de la vie chr\u00e9tienne (Les petits enfants, Les jeunes enfants et les p\u00e8res).<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Le b\u00e9b\u00e9 = le chr\u00e9tien charnel<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019ap\u00f4tre Jean nous pr\u00e9sente donc trois degr\u00e9s normaux de la vie chr\u00e9tienne. Maintenant, il faut bien comprendre qu\u2019il n\u2019y a rien de mal \u00e0 \u00eatre \u00e0 l\u2019un ou l\u2019autre des deux premiers stades. Par contre, il serait inqui\u00e9tant qu\u2019un jeune enfant ne grandisse pas pour devenir un adolescent et, enfin, un adulte. Il est tout aussi grave qu\u2019un chr\u00e9tien ne croisse pas pour devenir adulte dans la foi. Malheureusement, l\u2019ap\u00f4tre Paul nous montre que des chr\u00e9tiens courent le risque de rester \u00e0 l\u2019\u00e9tat d\u2019enfance. C\u2019est ce qu\u2019il avait observ\u00e9 chez les croyants de l\u2019\u00c9glise de Corinthe&nbsp;:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Pour ma part, fr\u00e8res et s\u0153urs, je n\u2019ai pas pu vous parler comme \u00e0 des personnes dirig\u00e9es par l\u2019Esprit, mais comme \u00e0 des personnes dirig\u00e9es par leur nature propre, comme \u00e0 de petits enfants en Christ. Je vous ai donn\u00e9 du lait, non de la nourriture solide, car vous ne pouviez pas la supporter. D\u2019ailleurs, m\u00eame maintenant vous ne le pouvez pas parce que vous \u00eates encore anim\u00e9s par votre nature. En effet, puisqu\u2019il y a parmi vous de la jalousie, des disputes [et des divisions], n\u2019\u00eates-vous pas dirig\u00e9s par votre nature propre et ne vous conduisez-vous pas d\u2019une mani\u00e8re tout humaine&nbsp;?<\/p>\n<cite><strong>1&nbsp;Corinthiens 3.1-3<\/strong><\/cite><\/blockquote>\n\n\n\n<h3 class=\"wp-block-heading\">Le drame : rester longtemps au stade de la petite enfance<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Quand Paul \u00e9tait arriv\u00e9 dans leur ville pour la premi\u00e8re fois, il n\u2019avait pas pu leur parler comme \u00e0 des chr\u00e9tiens matures. Cela \u00e9tait bien normal, puisqu\u2019ils venaient d\u2019entendre la Bonne Nouvelle de la bouche de l\u2019ap\u00f4tre. Ils l\u2019ont re\u00e7ue et, par l\u2019\u00c9vangile, ils sont n\u00e9s \u00e0 la vie de Dieu. Ils \u00e9taient donc de simples enfants en Christ, \u00e0 l\u2019\u00e9tape premi\u00e8re de la vie chr\u00e9tienne, comme la d\u00e9finit l\u2019ap\u00f4tre Jean, le disciple que J\u00e9sus aimait. L\u2019ap\u00f4tre ne leur enseigne d\u2019abord que les rudiments de la foi chr\u00e9tienne, parce que, encore nouveau-n\u00e9s, ils n\u2019\u00e9taient pas pr\u00eats \u00e0 affronter des questions plus profondes et plus difficiles. C\u2019\u00e9tait une condition normale et appropri\u00e9e pour eux \u00e0 l\u2019\u00e9poque. Au d\u00e9but, Paul n\u2019a pas pouss\u00e9 les jeunes croyants au-del\u00e0 de leurs capacit\u00e9s, mais leur a donn\u00e9 l\u2019enseignement qui \u00e9tait adapt\u00e9 \u00e0 leur \u00e9tat. Il n\u2019y avait rien de coupable \u00e0 ce qu\u2019ils ne soient pas encore pr\u00eats \u00e0 recevoir \u00ab&nbsp;une nourriture plus solide&nbsp;\u00bb, car ils ne pouvaient pas la supporter. Se manifestent ici le souci pastoral de l\u2019ap\u00f4tre Paul et sa capacit\u00e9 d\u2019adaptation aux besoins des chr\u00e9tiens. Mais le drame, c\u2019est que ces chr\u00e9tiens sont rest\u00e9s longtemps \u00e0 ce stade de la petite enfance. Paul a pass\u00e9 dix-huit mois \u00e0 Corinthe, suffisamment de temps donc pour leur enseigner les v\u00e9rit\u00e9s les plus pr\u00e9cieuses de la foi. Mais la difficult\u00e9 pour l\u2019ap\u00f4tre \u00e9tait que les Corinthiens n\u2019\u00e9taient pas encore pr\u00eats&nbsp;; il n\u2019a pas pu leur communiquer ces v\u00e9rit\u00e9s, il n\u2019a pas pu leur \u00ab&nbsp;parler comme \u00e0 des personnes dirig\u00e9es par l\u2019Esprit&nbsp;\u00bb (v.&nbsp;1), car cela demande de la maturit\u00e9. Paul s\u2019\u00e9tait adress\u00e9 \u00e0 eux, \u00ab&nbsp;comme \u00e0 des enfants en Christ&nbsp;\u00bb, pr\u00e9cis\u00e9ment comme \u00e0 des b\u00e9b\u00e9s&nbsp;; le mot employ\u00e9 ici est diff\u00e9rent de celui employ\u00e9 par Jean. Plus grave encore, m\u00eame au moment o\u00f9 il leur \u00e9crit, c\u2019est-\u00e0-dire des ann\u00e9es plus tard, l\u2019ap\u00f4tre sait qu\u2019ils sont rest\u00e9s des petits enfants en Christ&nbsp;: \u00ab&nbsp;D\u2019ailleurs, m\u00eame maintenant vous ne le pouvez pas parce que vous \u00eates encore anim\u00e9s par votre nature&nbsp;\u00bb (v.&nbsp;2-3) ou \u00ab&nbsp;parce que vous \u00eates encore charnels&nbsp;\u00bb (NEG). Ils auraient d\u00fb d\u00e9passer cet \u00e9tat depuis longtemps, mais ils y \u00e9taient <strong>encore<\/strong>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Un stade anormal<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Au lieu de devenir \u00ab&nbsp;des hommes spirituels&nbsp;\u00bb, ils \u00e9taient rest\u00e9s des chr\u00e9tiens charnels, inaugurant ainsi un quatri\u00e8me stade, anormal, dans lequel le chr\u00e9tien ne doit pas s\u2019aventurer&nbsp;: une marche selon la chair et non selon l\u2019Esprit. Cela est en opposition flagrante avec la vie normale du disciple de Christ, qui est une vie selon l\u2019Esprit. Alors qu\u2019ils auraient d\u00fb abandonner la mani\u00e8re de vivre du monde depuis longtemps, ils \u00e9taient rest\u00e9s immatures dans leur foi. Ils avaient continu\u00e9 de se conduire \u00e0 la mani\u00e8re des hommes laiss\u00e9s \u00e0 eux-m\u00eames. Voil\u00e0 pourquoi Paul leur dit qu\u2019ils marchent \u00ab&nbsp;selon l\u2019homme&nbsp;\u00bb (NEG). Cela veut dire qu\u2019ils se conduisent comme si l\u2019Esprit n\u2019avait aucune emprise sur leur vie.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Caract\u00e9ristiques du chr\u00e9tien charnel<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Regardons maintenant comment se caract\u00e9rise pr\u00e9cis\u00e9ment ce stade. Paul ne s\u2019est pas adress\u00e9 aux chr\u00e9tiens de Corinthe comme \u00e0 des chr\u00e9tiens matures, mais comme \u00e0 des hommes charnels&nbsp;: il s\u2019est restreint \u00e0 la simple pr\u00e9dication du salut, alors qu\u2019il aurait \u00e9t\u00e9 bien plus normal qu\u2019il aborde le dessein de Dieu dans le plan de salut\u2026 Certes, il a d\u00fb leur pr\u00e9senter les faits historiques et leur sens th\u00e9ologique, le fait que le salut \u00e9tait l\u2019accomplissement du plan divin. Fr\u00e9d\u00e9ric Godet identifie avec pr\u00e9cision ce lait que Paul leur a donn\u00e9&nbsp;: \u00ab&nbsp;Le lait d\u00e9signe la pr\u00e9dication de J\u00e9sus crucifi\u00e9, avec son contenu le plus simple et ses cons\u00e9quences les plus imm\u00e9diates, l\u2019expiation, la justification par la foi, la sanctification du croyant justifi\u00e9 par le Saint-Esprit, ce qui sauve en convertissant et r\u00e9g\u00e9n\u00e9rant&nbsp;\u00bb. Mais ce n\u2019est pas \u00e0 eux qu\u2019il aurait envoy\u00e9 la lettre aux \u00c9ph\u00e9siens, par exemple. Paul y d\u00e9veloppe le myst\u00e8re arr\u00eat\u00e9 de toute \u00e9ternit\u00e9, gard\u00e9 secret pendant les si\u00e8cles, r\u00e9alis\u00e9 par J\u00e9sus-Christ. Ce myst\u00e8re est d\u00e9ploy\u00e9 dans l\u2019\u00c9glise, r\u00e9alit\u00e9 universelle, \u00e0 la fois terrestre et c\u00e9leste\u2026 Voil\u00e0 de la nourriture solide, \u00ab&nbsp;ce que Paul vient d\u2019appeler la sagesse, la contemplation du plan divin dans son ensemble depuis la pr\u00e9destination \u00e9ternelle jusqu\u2019\u00e0 la consommation finale&nbsp;\u00bb. C\u2019est cette sagesse qu\u2019il pr\u00eache \u00ab&nbsp;parmi les parfaits&nbsp;\u00bb (1&nbsp;Corinthiens 2.6 \u2013&nbsp;NEG), c\u2019est-\u00e0-dire parmi les chr\u00e9tiens matures, dont la vie spirituelle est normalement d\u00e9velopp\u00e9e. Les chr\u00e9tiens de Corinthe \u00e9taient bien incapables, parce qu\u2019immatures, de saisir dans leur coh\u00e9rence, dans leur profondeur, dans leur richesse, les interventions de Dieu en Christ et, par lui, dans le monde. Voici donc la premi\u00e8re caract\u00e9ristique&nbsp;: l\u2019incapacit\u00e9 de comprendre ou m\u00eame de vouloir comprendre les r\u00e9alit\u00e9s profondes de la foi chr\u00e9tienne.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">L\u2019Esprit n\u2019a pas encore pris le contr\u00f4le&#8230; <\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Le chr\u00e9tien charnel a \u00e9t\u00e9 r\u00e9g\u00e9n\u00e9r\u00e9, il a re\u00e7u l\u2019Esprit, la vie nouvelle et le souffle de Dieu ont p\u00e9n\u00e9tr\u00e9 son c\u0153ur. Mais l\u2019Esprit n\u2019a pas encore pris le contr\u00f4le sur sa volont\u00e9 propre et sur les instincts de sa chair, sa pens\u00e9e n\u2019a pas encore \u00e9t\u00e9 enti\u00e8rement renouvel\u00e9e pour accepter les choses de Dieu et tout \u00e9valuer \u00e0 l\u2019aune de la nouvelle v\u00e9rit\u00e9. Ce chr\u00e9tien a exp\u00e9riment\u00e9 l\u2019influence de l\u2019Esprit, \u00ab&nbsp;mais il n\u2019est pas suffisamment conduit par sa puissance \u00e9clairante et sanctifiante&nbsp;: il pense, sent, juge, agit toujours selon la chair&nbsp;\u00bb. Sa volont\u00e9 consciente est encore entrav\u00e9e par des habitudes charnelles et \u00e9go\u00efstes, et sa capacit\u00e9 \u00e0 comprendre les fondements et les relations plus profondes de la v\u00e9rit\u00e9 chr\u00e9tienne n\u2019est pas encore d\u00e9velopp\u00e9e. Le chr\u00e9tien charnel est donc r\u00e9g\u00e9n\u00e9r\u00e9 par l\u2019Esprit de Dieu, mais il est encore un petit enfant se contentant de lait et incapable d\u2019assimiler la nourriture solide. Il est tout \u00e0 l\u2019oppos\u00e9 du chr\u00e9tien spirituel, qui marche selon l\u2019Esprit de Dieu, supporte et m\u00eame r\u00e9clame la nourriture solide qui a permis son d\u00e9veloppement et l\u2019a fait grandir pour devenir adulte et le rester.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Le chr\u00e9tien r\u00e9trograde<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Un autre passage de la Parole nous aide \u00e0 pr\u00e9ciser et d\u00e9velopper davantage ce que l\u2019ap\u00f4tre Jean nous a appris&nbsp;; il se trouve dans la lettre \u00e9crite aux H\u00e9breux. En m\u00eame temps, cette \u00e9p\u00eetre attire notre attention sur une menace r\u00e9elle&nbsp;: la stagnation ou, pire, la r\u00e9gression. C\u2019est ce dernier point que nous allons analyser maintenant. Voici donc ce qu\u2019\u00e9crit l\u2019auteur aux H\u00e9breux&nbsp;:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Nous avons beaucoup \u00e0 dire \u00e0 ce sujet, et des choses difficiles \u00e0 expliquer parce que vous \u00eates devenus lents \u00e0 comprendre. Alors que vous devriez avec le temps \u00eatre des enseignants, vous en \u00eates au point d\u2019avoir besoin qu\u2019on vous enseigne les \u00e9l\u00e9ments de base de la r\u00e9v\u00e9lation de Dieu&nbsp;; vous en \u00eates arriv\u00e9s \u00e0 avoir besoin de lait et non d\u2019une nourriture solide. Or celui qui en est au lait est inexp\u00e9riment\u00e9 dans la parole de justice, car il est un petit enfant. Mais la nourriture solide est pour les adultes, pour ceux qui, en raison de leur exp\u00e9rience, ont le jugement exerc\u00e9 \u00e0 discerner ce qui est bien et ce qui est mal.<\/p>\n<cite><strong>H\u00e9breux 5.11-14<\/strong><\/cite><\/blockquote>\n\n\n\n<h3 class=\"wp-block-heading\">Ils sont devenus lents \u00e0 comprendre&#8230;<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019auteur venait de parler, au d\u00e9but du chapitre 5.1-10, de J\u00e9sus comme Souverain sacrificateur selon l\u2019ordre de Melchis\u00e9dech. Il allait se lancer dans le d\u00e9veloppement de cette v\u00e9rit\u00e9 qu\u2019il jugeait capitale pour ses auditeurs&nbsp;: le sacerdoce c\u00e9leste de Christ et son sacrifice annonc\u00e9 par celui des animaux dans le temple de J\u00e9rusalem, sacrifice d\u2019autant plus excellent qu\u2019il purifie les consciences et fait acc\u00e9der au tr\u00f4ne de Dieu. L\u2019auteur, sous l\u2019autorit\u00e9 de l\u2019Esprit saint, est convaincu que l\u2019assimilation de ces composantes de la foi est n\u00e9cessaire pour le progr\u00e8s spirituel de ses auditeurs. Cela l\u2019a donc amen\u00e9 \u00e0 penser plus pr\u00e9cis\u00e9ment \u00e0 leur situation. Vont-ils pouvoir suivre&nbsp;? Sont-ils capables d\u2019appr\u00e9hender par l\u2019esprit ces \u00ab&nbsp;choses difficiles&nbsp;\u00bb qu\u2019il a encore \u00e0 leur expliquer au sujet du sacerdoce de Christ (v.&nbsp;11)&nbsp;? En fait ces chr\u00e9tiens sont devenus litt\u00e9ralement \u00ab&nbsp;paresseux quant aux oreilles&nbsp;\u00bb, c\u2019est-\u00e0-dire qu\u2019ils n\u2019ont plus cette intelligence spirituelle vive, ils ne supportent plus des enseignements exigeants, non qu\u2019ils aient un manque de capacit\u00e9 intellectuelle, mais leur sensibilit\u00e9 spirituelle s\u2019est \u00e9mouss\u00e9e avec le temps et les circonstances de la vie. Le diagnostic pos\u00e9 par l\u2019auteur n\u2019est pas apparu de mani\u00e8re soudaine, mais des indices dans les chapitres pr\u00e9c\u00e9dents laissaient d\u00e9j\u00e0 entendre que quelque chose ne va pas chez ses correspondants. Il les a d\u00e9j\u00e0 plusieurs fois encourag\u00e9s, exhort\u00e9s \u00e0 pers\u00e9v\u00e9rer, \u00e0 ne pas s\u2019endurcir. Avant d\u2019entrer donc dans ces lieux encore inexplor\u00e9s pour ses lecteurs, il va attirer leur attention sur leur situation. Il ne voudrait pas en effet que leurs oreilles se ferment d\u00e8s les premiers mots&nbsp;: \u00ab&nbsp;Nous avons beaucoup \u00e0 dire \u00e0 ce sujet, et des choses difficiles \u00e0 expliquer parce que vous \u00eates devenus lents \u00e0 comprendre&nbsp;\u00bb (v.&nbsp;11). Il craint qu\u2019ils r\u00e9agissent ainsi parce qu\u2019ils ont r\u00e9gress\u00e9 spirituellement.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Ils auraient d\u00fb \u00eatre \u00ab&nbsp;des ma\u00eetres&nbsp;\u00bb<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Chr\u00e9tiens depuis longtemps, ils auraient d\u00fb \u00eatre \u00ab&nbsp;des ma\u00eetres&nbsp;\u00bb, \u00ab&nbsp;des hommes faits&nbsp;\u00bb ou \u00ab&nbsp;des enseignants&nbsp;\u00bb, \u00ab&nbsp;des adultes&nbsp;\u00bb, c\u2019est-\u00e0-dire des hommes et des femmes qui ont atteint un haut degr\u00e9 dans le d\u00e9veloppement spirituel. Mais voil\u00e0 qu\u2019ils en sont encore aux \u00ab&nbsp;\u00e9l\u00e9ments de base de la r\u00e9v\u00e9lation de Dieu&nbsp;\u00bb. L\u2019auteur est parfaitement d\u2019accord avec Paul et Jean quant aux \u00e9tapes normales de la vie chr\u00e9tienne pour atteindre la maturit\u00e9. Voici ce qu\u2019il nous apprend au sujet des diff\u00e9rents stades&nbsp;:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Enfance ou commencement&nbsp;: Les jeunes chr\u00e9tiens dans la foi ont besoin de conna\u00eetre \u00ab&nbsp;les principes de base de la foi&nbsp;\u00bb. N\u2019\u00e9tant pas encore capables d\u2019assimiler certains enseignements, ils re\u00e7oivent du lait pour nourriture. C\u2019est le fondement sur lequel tout reposera ensuite.<\/li>\n\n\n\n<li>Progr\u00e8s&nbsp;: Gr\u00e2ce au lait, ces chr\u00e9tiens vont progresser en recevant une instruction qui ne se contentera pas de leur rappeler les bases, mais qui les conduira dans des domaines plus profonds, gr\u00e2ce \u00e0 une nourriture plus dense.<\/li>\n\n\n\n<li>Aboutissement&nbsp;: Le chr\u00e9tien est appel\u00e9, gr\u00e2ce \u00e0 une instruction \u00e9quilibr\u00e9e et avec le temps, \u00e0 devenir un enseignant, un ma\u00eetre. Cela veut dire que le chr\u00e9tien mature est une personne capable de transmettre des v\u00e9rit\u00e9s spirituelles qu\u2019elle a parfaitement saisies (non en ayant n\u00e9cessairement un statut officiel, mais au moins en aidant les autres dans un cadre un \u00e0 un, par exemple). C\u2019est un homme ou une femme au savoir s\u00fbr, apte \u00e0 aider les plus jeunes dans la foi. Voil\u00e0 ce qui fait de ce chr\u00e9tien un adulte, un chr\u00e9tien qui a atteint le stade de la maturit\u00e9.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Mais ce n\u2019est pas le chemin qu\u2019ont suivi les destinataires de la lettre. Ils n\u2019ont pas connu de progr\u00e8s spirituel, mais plut\u00f4t une r\u00e9gression, un retour \u00e0 l\u2019\u00e9tat d\u2019enfance. Ils ont arr\u00eat\u00e9 de progresser et ont ainsi perdu pied&nbsp;:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La vie chr\u00e9tienne ressemble beaucoup \u00e0 l\u2019escalade d\u2019une montagne de glace. Vous ne pouvez pas glisser vers le haut. Vous devez assurer chaque \u00e9tape avec un piolet. Ce n\u2019est qu\u2019avec un travail incessant de coupe et de taille que vous pouvez progresser. Si vous voulez savoir comment r\u00e9trograder, arr\u00eatez d\u2019aller de l\u2019avant. Cessez de monter et vous descendrez par n\u00e9cessit\u00e9. Vous ne pouvez jamais rester immobile<a href=\"#_ftn9\" id=\"_ftnref9\">[9]<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">D\u00e9sirant arracher les auditeurs \u00e0 leur pauvret\u00e9 spirituelle et les faire progresser dans la connaissance du message chr\u00e9tien dans toute sa richesse, l\u2019auteur n\u2019a pas renonc\u00e9 \u00e0 leur pr\u00e9senter les enseignements primordiaux pour qu\u2019ils avancent dans la foi et parviennent \u00e0 la maturit\u00e9. Il nous encourage aussi \u00e0 faire de cette maturit\u00e9 l\u2019objet de notre \u00e9lan et l\u2019orientation de notre c\u0153ur et de notre vie&nbsp;: <\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">C\u2019est pourquoi, laissant les bases de l\u2019enseignement relatif au Messie, tendons vers la maturit\u00e9 sans avoir \u00e0 reposer le fondement du renoncement aux \u0153uvres mortes, de la foi en Dieu, de l\u2019enseignement concernant les bapt\u00eames et l\u2019imposition des mains, de la r\u00e9surrection des morts et du jugement \u00e9ternel. <\/p>\n<cite><strong>H\u00e9breux 6.1-2<\/strong><\/cite><\/blockquote>\n\n\n\n<h3 class=\"wp-block-heading\">Tendons vers la maturit\u00e9<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Il y a des v\u00e9rit\u00e9s profondes, difficiles \u00e0 saisir du premier coup et qui demandent donc de l\u2019attention et des efforts. Le but n\u2019est pas de se faire une grosse t\u00eate, mais un c\u0153ur ob\u00e9issant, qui sait faire la diff\u00e9rence entre le bien et le mal. \u00ab&nbsp;Tendons vers la maturit\u00e9&nbsp;\u00bb, c\u2019est-\u00e0-dire vers l\u2019intelligence du sacrifice du Christ, sa place et son r\u00f4le au ciel, sa m\u00e9diation, sa souveraine pr\u00eatrise&nbsp;: c\u2019est l\u2019invitation pressante que Dieu adresse \u00e0 tout chr\u00e9tien. Le d\u00e9but de la vie chr\u00e9tienne se caract\u00e9rise par un enseignement des rudiments de la Parole de Dieu, un enseignement excellent en soi, mais qui doit \u00eatre d\u00e9pass\u00e9. Nous sommes appel\u00e9s \u00e0 d\u00e9passer l\u2019enseignement \u00e9l\u00e9mentaire pour rechercher la nourriture solide qui fera de nous des chr\u00e9tiens matures. Ce dernier stade est le degr\u00e9 normal d\u2019aboutissement de tout chr\u00e9tien qui a un certain nombre d\u2019ann\u00e9es de vie chr\u00e9tienne. Or, ce stade ne peut \u00eatre atteint sans un r\u00e9el approfondissement des v\u00e9rit\u00e9s spirituelles. Malheureusement, la tendance aujourd\u2019hui est \u00e0 la n\u00e9gligence de la connaissance, voire au refus des enseignements approfondis. Cette position ne peut que produire des nains spirituels. \u00ab&nbsp;Surtout pas de doctrine&nbsp;!&nbsp;\u00bb disent certains. Mais affirmer cela, c\u2019est dire que nous n\u2019avons pas besoin d\u2019enseignement. Or, justement, l\u2019auteur lie \u00e9troitement enseignement approfondi et d\u00e9veloppement spirituel ou v\u00e9rit\u00e9s ardues et croissance dans la foi. Il est urgent de voir le lien entre nourriture solide et maturit\u00e9, entre connaissance de Dieu et croissance.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\">Reproduction interdite sans autorisation \u00e9crite des \u00c9ditions Cl\u00e9. Copyright 2023.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\" style=\"grid-template-columns:28% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"719\" height=\"1024\" src=\"https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2023\/02\/0161.ip_-719x1024.jpg\" alt=\"\" class=\"wp-image-2870 size-full\" srcset=\"https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2023\/02\/0161.ip_-719x1024.jpg 719w, https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2023\/02\/0161.ip_-211x300.jpg 211w, https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2023\/02\/0161.ip_-77x110.jpg 77w, https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2023\/02\/0161.ip_-295x420.jpg 295w, https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2023\/02\/0161.ip_-302x430.jpg 302w, https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2023\/02\/0161.ip_.jpg 758w\" sizes=\"auto, (max-width: 719px) 100vw, 719px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"wp-block-paragraph\">D\u00e9couvrez le livre de <a href=\"https:\/\/editionscle.com\/544-jamel-attar\">Jamel Attar<\/a> chez votre libraire ou sur notre <a href=\"https:\/\/editionscle.com\/%C3%A0-para%C3%AEtre\/342-le-chr%C3%A9tien-mature-9782358431613.html\">boutique<\/a><\/p>\n<\/div><\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Entretien avec Jamel ATTAR - \u00abLe Chr\u00e9tien mature\u00bb - Nouveau livre aux \u00c9ditions Cl\u00e9\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/BBNiEM57qBU?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><figcaption class=\"wp-element-caption\">Vid\u00e9o entretien avec Jamel Attar a propos de son livre (10:40)<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Nous reproduisons ici la suite de et fin de l&rsquo;extrait du livre Le chr\u00e9tien mature de Jamel Attar publi\u00e9 aux \u00c9ditions Cl\u00e9. Les stades anormaux de la vie chr\u00e9tienne&nbsp; Voir la partie 1 de l&rsquo;article pour les 3 degr\u00e9s normaux de la vie chr\u00e9tienne (Les petits enfants, Les jeunes enfants et les p\u00e8res). Le b\u00e9b\u00e9 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2901,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,72,68],"tags":[169,172],"class_list":["post-2893","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite","category-articles","category-extrait","tag-attar","tag-le-chretien-mature"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les \u00e9tapes vers la maturit\u00e9 chr\u00e9tienne par Jamel ATTAR (2\/2) - Blog des \u00c9ditions Cl\u00e9<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogs.editionscle.com\/blogcle\/les-etapes-vers-la-maturite-chretienne-par-jamel-attar-2-2\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les \u00e9tapes vers la maturit\u00e9 chr\u00e9tienne par Jamel ATTAR (2\/2) - Blog des \u00c9ditions Cl\u00e9\" \/>\n<meta property=\"og:description\" content=\"Nous reproduisons ici la suite de et fin de l&rsquo;extrait du livre Le chr\u00e9tien mature de Jamel Attar publi\u00e9 aux \u00c9ditions Cl\u00e9. Les stades anormaux de la vie chr\u00e9tienne&nbsp; Voir la partie 1 de l&rsquo;article pour les 3 degr\u00e9s normaux de la vie chr\u00e9tienne (Les petits enfants, Les jeunes enfants et les p\u00e8res). Le b\u00e9b\u00e9 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogs.editionscle.com\/blogcle\/les-etapes-vers-la-maturite-chretienne-par-jamel-attar-2-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog des \u00c9ditions Cl\u00e9\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/editionscle\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-17T17:49:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-17T18:00:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2023\/02\/frise-lcm-2-reduite-Partie-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"841\" \/>\n\t<meta property=\"og:image:height\" content=\"288\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"\u00c9ditions Cl\u00e9\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@editionscle\" \/>\n<meta name=\"twitter:site\" content=\"@editionscle\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u00c9ditions Cl\u00e9\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"14 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/les-etapes-vers-la-maturite-chretienne-par-jamel-attar-2-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/les-etapes-vers-la-maturite-chretienne-par-jamel-attar-2-2\\\/\"},\"author\":{\"name\":\"\u00c9ditions Cl\u00e9\",\"@id\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/#\\\/schema\\\/person\\\/6f614e2cdd8aac468261bff8219ca7a0\"},\"headline\":\"Les \u00e9tapes vers la maturit\u00e9 chr\u00e9tienne par Jamel ATTAR (2\\\/2)\",\"datePublished\":\"2023-02-17T17:49:08+00:00\",\"dateModified\":\"2023-02-17T18:00:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/les-etapes-vers-la-maturite-chretienne-par-jamel-attar-2-2\\\/\"},\"wordCount\":2928,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/les-etapes-vers-la-maturite-chretienne-par-jamel-attar-2-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/02\\\/frise-lcm-2-reduite-Partie-2.jpg\",\"keywords\":[\"Attar\",\"le chretien mature\"],\"articleSection\":[\"Actualit\u00e9\",\"Articles\",\"Extrait\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/les-etapes-vers-la-maturite-chretienne-par-jamel-attar-2-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/les-etapes-vers-la-maturite-chretienne-par-jamel-attar-2-2\\\/\",\"url\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/les-etapes-vers-la-maturite-chretienne-par-jamel-attar-2-2\\\/\",\"name\":\"Les \u00e9tapes vers la maturit\u00e9 chr\u00e9tienne par Jamel ATTAR (2\\\/2) - Blog des \u00c9ditions Cl\u00e9\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/les-etapes-vers-la-maturite-chretienne-par-jamel-attar-2-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/les-etapes-vers-la-maturite-chretienne-par-jamel-attar-2-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/02\\\/frise-lcm-2-reduite-Partie-2.jpg\",\"datePublished\":\"2023-02-17T17:49:08+00:00\",\"dateModified\":\"2023-02-17T18:00:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/les-etapes-vers-la-maturite-chretienne-par-jamel-attar-2-2\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/les-etapes-vers-la-maturite-chretienne-par-jamel-attar-2-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/les-etapes-vers-la-maturite-chretienne-par-jamel-attar-2-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/02\\\/frise-lcm-2-reduite-Partie-2.jpg\",\"contentUrl\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/02\\\/frise-lcm-2-reduite-Partie-2.jpg\",\"width\":841,\"height\":288},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/les-etapes-vers-la-maturite-chretienne-par-jamel-attar-2-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les \u00e9tapes vers la maturit\u00e9 chr\u00e9tienne par Jamel ATTAR (2\\\/2)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/#website\",\"url\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/\",\"name\":\"Blog des \u00c9ditions Cl\u00e9\",\"description\":\"Livres et logiciels pour comprendre la Bible\",\"publisher\":{\"@id\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/#organization\",\"name\":\"Editions Cl\u00e9\",\"url\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/03\\\/Profil_facebookcle.png\",\"contentUrl\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/03\\\/Profil_facebookcle.png\",\"width\":375,\"height\":375,\"caption\":\"Editions Cl\u00e9\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/editionscle\",\"https:\\\/\\\/x.com\\\/editionscle\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/EditionsCle\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/#\\\/schema\\\/person\\\/6f614e2cdd8aac468261bff8219ca7a0\",\"name\":\"\u00c9ditions Cl\u00e9\",\"description\":\"\u00c9ditions Cl\u00e9\",\"sameAs\":[\"https:\\\/\\\/editionscle.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les \u00e9tapes vers la maturit\u00e9 chr\u00e9tienne par Jamel ATTAR (2\/2) - Blog des \u00c9ditions Cl\u00e9","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogs.editionscle.com\/blogcle\/les-etapes-vers-la-maturite-chretienne-par-jamel-attar-2-2\/","og_locale":"fr_FR","og_type":"article","og_title":"Les \u00e9tapes vers la maturit\u00e9 chr\u00e9tienne par Jamel ATTAR (2\/2) - Blog des \u00c9ditions Cl\u00e9","og_description":"Nous reproduisons ici la suite de et fin de l&rsquo;extrait du livre Le chr\u00e9tien mature de Jamel Attar publi\u00e9 aux \u00c9ditions Cl\u00e9. Les stades anormaux de la vie chr\u00e9tienne&nbsp; Voir la partie 1 de l&rsquo;article pour les 3 degr\u00e9s normaux de la vie chr\u00e9tienne (Les petits enfants, Les jeunes enfants et les p\u00e8res). Le b\u00e9b\u00e9 [&hellip;]","og_url":"https:\/\/blogs.editionscle.com\/blogcle\/les-etapes-vers-la-maturite-chretienne-par-jamel-attar-2-2\/","og_site_name":"Blog des \u00c9ditions Cl\u00e9","article_publisher":"https:\/\/www.facebook.com\/editionscle","article_published_time":"2023-02-17T17:49:08+00:00","article_modified_time":"2023-02-17T18:00:38+00:00","og_image":[{"width":841,"height":288,"url":"https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2023\/02\/frise-lcm-2-reduite-Partie-2.jpg","type":"image\/jpeg"}],"author":"\u00c9ditions Cl\u00e9","twitter_card":"summary_large_image","twitter_creator":"@editionscle","twitter_site":"@editionscle","twitter_misc":{"\u00c9crit par":"\u00c9ditions Cl\u00e9","Dur\u00e9e de lecture estim\u00e9e":"14 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blogs.editionscle.com\/blogcle\/les-etapes-vers-la-maturite-chretienne-par-jamel-attar-2-2\/#article","isPartOf":{"@id":"https:\/\/blogs.editionscle.com\/blogcle\/les-etapes-vers-la-maturite-chretienne-par-jamel-attar-2-2\/"},"author":{"name":"\u00c9ditions Cl\u00e9","@id":"https:\/\/blogs.editionscle.com\/blogcle\/#\/schema\/person\/6f614e2cdd8aac468261bff8219ca7a0"},"headline":"Les \u00e9tapes vers la maturit\u00e9 chr\u00e9tienne par Jamel ATTAR (2\/2)","datePublished":"2023-02-17T17:49:08+00:00","dateModified":"2023-02-17T18:00:38+00:00","mainEntityOfPage":{"@id":"https:\/\/blogs.editionscle.com\/blogcle\/les-etapes-vers-la-maturite-chretienne-par-jamel-attar-2-2\/"},"wordCount":2928,"commentCount":0,"publisher":{"@id":"https:\/\/blogs.editionscle.com\/blogcle\/#organization"},"image":{"@id":"https:\/\/blogs.editionscle.com\/blogcle\/les-etapes-vers-la-maturite-chretienne-par-jamel-attar-2-2\/#primaryimage"},"thumbnailUrl":"https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2023\/02\/frise-lcm-2-reduite-Partie-2.jpg","keywords":["Attar","le chretien mature"],"articleSection":["Actualit\u00e9","Articles","Extrait"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blogs.editionscle.com\/blogcle\/les-etapes-vers-la-maturite-chretienne-par-jamel-attar-2-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blogs.editionscle.com\/blogcle\/les-etapes-vers-la-maturite-chretienne-par-jamel-attar-2-2\/","url":"https:\/\/blogs.editionscle.com\/blogcle\/les-etapes-vers-la-maturite-chretienne-par-jamel-attar-2-2\/","name":"Les \u00e9tapes vers la maturit\u00e9 chr\u00e9tienne par Jamel ATTAR (2\/2) - Blog des \u00c9ditions Cl\u00e9","isPartOf":{"@id":"https:\/\/blogs.editionscle.com\/blogcle\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blogs.editionscle.com\/blogcle\/les-etapes-vers-la-maturite-chretienne-par-jamel-attar-2-2\/#primaryimage"},"image":{"@id":"https:\/\/blogs.editionscle.com\/blogcle\/les-etapes-vers-la-maturite-chretienne-par-jamel-attar-2-2\/#primaryimage"},"thumbnailUrl":"https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2023\/02\/frise-lcm-2-reduite-Partie-2.jpg","datePublished":"2023-02-17T17:49:08+00:00","dateModified":"2023-02-17T18:00:38+00:00","breadcrumb":{"@id":"https:\/\/blogs.editionscle.com\/blogcle\/les-etapes-vers-la-maturite-chretienne-par-jamel-attar-2-2\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blogs.editionscle.com\/blogcle\/les-etapes-vers-la-maturite-chretienne-par-jamel-attar-2-2\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blogs.editionscle.com\/blogcle\/les-etapes-vers-la-maturite-chretienne-par-jamel-attar-2-2\/#primaryimage","url":"https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2023\/02\/frise-lcm-2-reduite-Partie-2.jpg","contentUrl":"https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2023\/02\/frise-lcm-2-reduite-Partie-2.jpg","width":841,"height":288},{"@type":"BreadcrumbList","@id":"https:\/\/blogs.editionscle.com\/blogcle\/les-etapes-vers-la-maturite-chretienne-par-jamel-attar-2-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/blogs.editionscle.com\/blogcle\/"},{"@type":"ListItem","position":2,"name":"Les \u00e9tapes vers la maturit\u00e9 chr\u00e9tienne par Jamel ATTAR (2\/2)"}]},{"@type":"WebSite","@id":"https:\/\/blogs.editionscle.com\/blogcle\/#website","url":"https:\/\/blogs.editionscle.com\/blogcle\/","name":"Blog des \u00c9ditions Cl\u00e9","description":"Livres et logiciels pour comprendre la Bible","publisher":{"@id":"https:\/\/blogs.editionscle.com\/blogcle\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogs.editionscle.com\/blogcle\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/blogs.editionscle.com\/blogcle\/#organization","name":"Editions Cl\u00e9","url":"https:\/\/blogs.editionscle.com\/blogcle\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blogs.editionscle.com\/blogcle\/#\/schema\/logo\/image\/","url":"https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2018\/03\/Profil_facebookcle.png","contentUrl":"https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2018\/03\/Profil_facebookcle.png","width":375,"height":375,"caption":"Editions Cl\u00e9"},"image":{"@id":"https:\/\/blogs.editionscle.com\/blogcle\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/editionscle","https:\/\/x.com\/editionscle","https:\/\/www.youtube.com\/user\/EditionsCle"]},{"@type":"Person","@id":"https:\/\/blogs.editionscle.com\/blogcle\/#\/schema\/person\/6f614e2cdd8aac468261bff8219ca7a0","name":"\u00c9ditions Cl\u00e9","description":"\u00c9ditions Cl\u00e9","sameAs":["https:\/\/editionscle.com"]}]}},"_links":{"self":[{"href":"https:\/\/blogs.editionscle.com\/blogcle\/wp-json\/wp\/v2\/posts\/2893","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.editionscle.com\/blogcle\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.editionscle.com\/blogcle\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.editionscle.com\/blogcle\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.editionscle.com\/blogcle\/wp-json\/wp\/v2\/comments?post=2893"}],"version-history":[{"count":3,"href":"https:\/\/blogs.editionscle.com\/blogcle\/wp-json\/wp\/v2\/posts\/2893\/revisions"}],"predecessor-version":[{"id":2899,"href":"https:\/\/blogs.editionscle.com\/blogcle\/wp-json\/wp\/v2\/posts\/2893\/revisions\/2899"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.editionscle.com\/blogcle\/wp-json\/wp\/v2\/media\/2901"}],"wp:attachment":[{"href":"https:\/\/blogs.editionscle.com\/blogcle\/wp-json\/wp\/v2\/media?parent=2893"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.editionscle.com\/blogcle\/wp-json\/wp\/v2\/categories?post=2893"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.editionscle.com\/blogcle\/wp-json\/wp\/v2\/tags?post=2893"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}