{"id":3383,"date":"2026-01-21T15:45:11","date_gmt":"2026-01-21T14:45:11","guid":{"rendered":"https:\/\/blogs.editionscle.com\/blogcle\/?p=3383"},"modified":"2026-01-21T16:05:50","modified_gmt":"2026-01-21T15:05:50","slug":"difference-catholique-protestant-la-question-de-lautorite-extrait-du-livre-de-william-clayton","status":"publish","type":"post","link":"https:\/\/blogs.editionscle.com\/blogcle\/difference-catholique-protestant-la-question-de-lautorite-extrait-du-livre-de-william-clayton\/","title":{"rendered":"Diff\u00e9rence catholique \/ protestant : La question de l\u2019autorit\u00e9 (extrait du livre de William Clayton)"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2026\/01\/akira-hojo-_86u_Y0oAaM-unsplash-1-1024x683.jpg\" alt=\"Photo de Akira Hojo sur Unsplash\" class=\"wp-image-3386\" srcset=\"https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2026\/01\/akira-hojo-_86u_Y0oAaM-unsplash-1-1024x683.jpg 1024w, https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2026\/01\/akira-hojo-_86u_Y0oAaM-unsplash-1-300x200.jpg 300w, https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2026\/01\/akira-hojo-_86u_Y0oAaM-unsplash-1-768x512.jpg 768w, https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2026\/01\/akira-hojo-_86u_Y0oAaM-unsplash-1-1536x1024.jpg 1536w, https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2026\/01\/akira-hojo-_86u_Y0oAaM-unsplash-1-2048x1365.jpg 2048w, https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2026\/01\/akira-hojo-_86u_Y0oAaM-unsplash-1-110x73.jpg 110w, https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2026\/01\/akira-hojo-_86u_Y0oAaM-unsplash-1-420x280.jpg 420w, https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2026\/01\/akira-hojo-_86u_Y0oAaM-unsplash-1-645x430.jpg 645w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">L&rsquo;autorit\u00e9 en mati\u00e8re de foi et de m\u0153urs<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Abordons ce th\u00e8me de mani\u00e8re simple. Si on demandait \u00e0 un catholique instruit&nbsp;: \u00ab&nbsp;Pourquoi croyez-vous ceci ou cela&nbsp;?&nbsp;\u00bb, il r\u00e9pondrait&nbsp;: \u00ab&nbsp;Parce que l\u2019\u00c9glise l\u2019enseigne&nbsp;\u00bb. En disant cela, il exprime l\u2019optique catholique selon laquelle l\u2019autorit\u00e9 r\u00e9side, en dernier ressort, dans l\u2019\u00c9glise elle-m\u00eame.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si l\u2019on posait la m\u00eame question \u00e0 un protestant \u00e9vang\u00e9lique, il r\u00e9pondrait&nbsp;: \u00ab&nbsp;Parce que la Bible le dit&nbsp;\u00bb. Voil\u00e0, en un mot, la diff\u00e9rence entre les deux conceptions. Tout d\u00e9pend de la source qui fait autorit\u00e9.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><a><\/a>La position catholique<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Pour \u00eatre plus exact, les documents officiels de l\u2019\u00c9glise Catholique se r\u00e9f\u00e8rent \u00e0 une double source d\u2019autorit\u00e9 en mati\u00e8re de foi et de vie chr\u00e9tiennes. Cette position&nbsp;est r\u00e9sum\u00e9e, par exemple, en <a href=\"https:\/\/www.vatican.va\/archive\/hist_councils\/ii_vatican_council\/documents\/vat-ii_const_19651118_dei-verbum_fr.html\"><em>Dei Verbum<\/em> 21<\/a>&nbsp;: \u00ab&nbsp;<em>L\u2019\u00c9glise a toujours v\u00e9n\u00e9r\u00e9 les divines \u00c9critures [\u2026] Toujours elle eut et elle a pour r\u00e8gle supr\u00eame de sa foi les \u00c9critures, conjointement avec la Sainte Tradition&nbsp;\u00bb<\/em>. Cette source de r\u00e9v\u00e9lation est compos\u00e9e donc de deux \u00e9l\u00e9ments&nbsp;: l\u2019\u00c9criture sainte <strong>conjointement avec<\/strong> la Tradition de l\u2019\u00c9glise.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>L\u2019\u00c9criture Sainte<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Les livres de l\u2019Ancien et du Nouveau Testaments ayant \u00e9t\u00e9 \u00ab&nbsp;<em>r\u00e9dig\u00e9s sous l\u2019inspiration de l\u2019Esprit Saint, ont Dieu pour auteur<\/em>&nbsp;\u00bb&nbsp;; les auteurs humains ont mis par \u00e9crit \u00ab&nbsp;<em>tout ce qui \u00e9tait conforme \u00e0 son d\u00e9sir, et cela seulement<\/em>&nbsp;\u00bb. \u00ab&nbsp;<em>Les livres de l\u2019\u00c9criture enseignent fermement, fid\u00e8lement et sans erreur la v\u00e9rit\u00e9 que Dieu pour notre salut a voulu voir consign\u00e9e dans les Lettres sacr\u00e9es&nbsp;\u00bb<\/em> (<a href=\"https:\/\/www.vatican.va\/archive\/hist_councils\/ii_vatican_council\/documents\/vat-ii_const_19651118_dei-verbum_fr.html\"><em>Dei Verbum<\/em> 11<\/a>). Les \u00e9vang\u00e9liques partagent pleinement ces convictions.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>La Sainte Tradition<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c0 travers les si\u00e8cles, l\u2019\u00c9glise a d\u00e9velopp\u00e9 sa compr\u00e9hension de la r\u00e9v\u00e9lation biblique, et sa transmission s\u2019appelle la Tradition. Par elle, <em>\u00ab&nbsp;l\u2019\u00c9glise perp\u00e9tue dans sa doctrine, sa vie et son culte et elle transmet \u00e0 chaque g\u00e9n\u00e9ration, tout ce qu\u2019elle est elle-m\u00eame, tout ce qu\u2019elle croit&nbsp;\u00bb<\/em> (<em>Dei Verbum<\/em> 8).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Tradition&nbsp;Catholique est compos\u00e9e de trois \u00e9l\u00e9ments&nbsp;:<\/p>\n\n\n\n<ol start=\"1\" class=\"wp-block-list\">\n<li>Les enseignements des P\u00e8res de l\u2019\u00c9glise, c\u2019est-\u00e0-dire certains docteurs chr\u00e9tiens des premiers si\u00e8cles&nbsp;;<\/li>\n\n\n\n<li>Les d\u00e9crets des Conciles de l\u2019\u00c9glise \u00e0 travers son histoire, dont le dernier fut Vatican II&nbsp;;<\/li>\n\n\n\n<li>L\u2019enseignement du Magist\u00e8re de l\u2019\u00c9glise (c\u2019est-\u00e0-dire l\u2019autorit\u00e9 enseignante), dont le pape est le porte-parole infaillible. Cela inclut donc les encycliques papales et tout dogme que d\u00e9finirait le pape.<\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">Voici comment Vatican II a formul\u00e9 sa source d\u2019autorit\u00e9&nbsp;: \u00ab&nbsp;La Sainte Tradition et la Sainte \u00c9criture sont reli\u00e9es et [\u2026] ne forment pour ainsi dire qu\u2019un tout&nbsp;\u00bb (<a href=\"https:\/\/www.vatican.va\/archive\/hist_councils\/ii_vatican_council\/documents\/vat-ii_const_19651118_dei-verbum_fr.html\">Dei Verbum 9<\/a>). \u00ab&nbsp;La Sainte Tradition et la Sainte \u00c9criture constituent un unique d\u00e9p\u00f4t sacr\u00e9 de la parole de Dieu&nbsp;\u00bb (<a href=\"https:\/\/www.vatican.va\/archive\/hist_councils\/ii_vatican_council\/documents\/vat-ii_const_19651118_dei-verbum_fr.html\">Dei Verbum 10<\/a>). Il en r\u00e9sulte que l\u2019\u00c9glise \u00ab&nbsp;ne tire pas de la seule \u00c9criture Sainte sa certitude sur tous les points de la r\u00e9v\u00e9lation. C\u2019est pourquoi l\u2019une et l\u2019autre doivent \u00eatre re\u00e7ues et v\u00e9n\u00e9r\u00e9es avec un \u00e9gal sentiment d\u2019amour et de respect&nbsp;\u00bb (<a href=\"https:\/\/www.vatican.va\/archive\/hist_councils\/ii_vatican_council\/documents\/vat-ii_const_19651118_dei-verbum_fr.html\">Dei Verbum 9<\/a>). En clair, la Tradition est tout autant source d\u2019autorit\u00e9 que l\u2019\u00c9criture.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En ce qui concerne la place du Magist\u00e8re, l\u2019autorit\u00e9 enseignante officielle de l\u2019\u00c9glise Catholique, Vatican II (qui fait partie du Magist\u00e8re, car ses documents formulent la doctrine officielle) s\u2019exprime ainsi&nbsp;: \u00ab&nbsp;<em>La charge d\u2019interpr\u00e9ter de fa\u00e7on authentique la parole de Dieu, \u00e9crite ou transmise, a \u00e9t\u00e9 confi\u00e9e au seul Magist\u00e8re vivant de l\u2019\u00c9glise [\u2026] Il est donc clair que la Sainte Tradition, la Sainte \u00c9criture et le Magist\u00e8re de l\u2019\u00c9glise [\u2026] sont tellement reli\u00e9s et solidaires entre eux, qu\u2019aucune de ses r\u00e9alit\u00e9s ne subsiste sans les autres<\/em>&nbsp;\u00bb. Le Magist\u00e8re \u00ab&nbsp;<em>puise en cet unique d\u00e9p\u00f4t de la foi tout ce qu\u2019il propose \u00e0 croire comme \u00e9tant r\u00e9v\u00e9l\u00e9 par Dieu<\/em>&nbsp;\u00bb (<a href=\"https:\/\/www.vatican.va\/archive\/hist_councils\/ii_vatican_council\/documents\/vat-ii_const_19651118_dei-verbum_fr.html\"><em>Dei Verbum<\/em> 10<\/a>).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Voil\u00e0 pourquoi, en fin de compte, le catholique croit \u00e0 ce que l\u2019\u00c9glise lui dit. L\u2019autorit\u00e9 pour ses croyances est l\u2019\u00c9glise qui, par son Magist\u00e8re, \u00ab&nbsp;propose, sous une forme obligeant le peuple chr\u00e9tien \u00e0 une adh\u00e9sion irr\u00e9vocable de foi, des v\u00e9rit\u00e9s contenues dans la R\u00e9v\u00e9lation divine&nbsp;\u00bb (<a href=\"https:\/\/www.vatican.va\/archive\/FRA0013\/_INDEX.HTM\"><em>Cat\u00e9chisme<\/em> \u00a788<\/a>). Le catholique doit croire que le Magist\u00e8re seul est habilit\u00e9 \u00e0 donner l\u2019interpr\u00e9tation authentique de la r\u00e9v\u00e9lation venant donc de cet ensemble que constituent Bible et Tradition.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><a><\/a>L\u2019optique des protestants<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Les protestants, en revanche, se sont bas\u00e9s, lors de la R\u00e9forme, sur le grand principe \u00ab&nbsp;<em>Sola Scriptura<\/em>&nbsp;\u00bb, c\u2019est-\u00e0-dire la Bible comme autorit\u00e9 supr\u00eame en mati\u00e8re de foi et de vie chr\u00e9tiennes. Toute autre pr\u00e9tendue autorit\u00e9 doit \u00eatre soumise \u00e0 celle des \u00c9critures, tout enseignement donn\u00e9 dans l\u2019\u00c9glise doit ressortir comme une \u00e9vidence&nbsp;de la seule Parole biblique. Les doctrines de tout docteur, p\u00e8re de l\u2019\u00c9glise, th\u00e9ologien ou pape, doivent \u00eatre examin\u00e9es \u00e0 la lumi\u00e8re de l\u2019\u00c9criture. Les r\u00e9formateurs suivirent le principe de passer au crible de la Bible toutes les pratiques, les enseignements et les dogmes de l\u2019\u00c9glise. Seul ce que la Bible enseigne peut \u00eatre re\u00e7u comme \u00e9tant la v\u00e9rit\u00e9 issue de la r\u00e9v\u00e9lation de Dieu.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">C\u2019est en suivant ce principe que les protestants ont \u00e9tabli leurs doctrines. Certaines de celles-ci s\u2019accordent, comme nous avons vu, avec l\u2019enseignement biblique de l\u2019\u00c9glise Catholique. Toutes les doctrines divergentes proviennent du fait que les deux communions puisent leur enseignement de deux sources d\u2019autorit\u00e9 distinctes. <em>(fin de l&rsquo;extrait du livre)<\/em>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>La reproduction de cet article est interdite sur tout support. Copyright&nbsp;<a href=\"https:\/\/timothykeller.com\/\">William Clayton<\/a>&nbsp;et \u00c9ditions Cl\u00e9<\/em><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile\" style=\"grid-template-columns:34% auto\"><figure class=\"wp-block-media-text__media\"><a href=\"https:\/\/editionscle.com\/559-william-clayton\"><img loading=\"lazy\" decoding=\"async\" width=\"689\" height=\"1024\" src=\"https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2026\/01\/0183.ip-cadre-689x1024.jpg\" alt=\"\" class=\"wp-image-3384 size-full\" srcset=\"https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2026\/01\/0183.ip-cadre-689x1024.jpg 689w, https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2026\/01\/0183.ip-cadre-202x300.jpg 202w, https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2026\/01\/0183.ip-cadre-74x110.jpg 74w, https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2026\/01\/0183.ip-cadre-283x420.jpg 283w, https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2026\/01\/0183.ip-cadre-289x430.jpg 289w, https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2026\/01\/0183.ip-cadre.jpg 726w\" sizes=\"auto, (max-width: 689px) 100vw, 689px\" \/><\/a><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"wp-block-paragraph\">D\u00e9couvrez le livre de William CLAYTON sur notre <a href=\"https:\/\/editionscle.com\/559-william-clayton\">boutique <\/a>ou dans votre librairie chr\u00e9tienne pr\u00e9f\u00e9r\u00e9e.<\/p>\n\n\n<div class=\"wp-block-image is-style-rounded wp-duotone-unset-1\">\n<figure class=\"alignright size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"525\" height=\"700\" src=\"https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2026\/01\/PhotoWilliamClayton2009.jpg\" alt=\"\" class=\"wp-image-3395\" style=\"width:171px;height:auto\" srcset=\"https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2026\/01\/PhotoWilliamClayton2009.jpg 525w, https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2026\/01\/PhotoWilliamClayton2009-225x300.jpg 225w, https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2026\/01\/PhotoWilliamClayton2009-83x110.jpg 83w, https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2026\/01\/PhotoWilliamClayton2009-315x420.jpg 315w, https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2026\/01\/PhotoWilliamClayton2009-323x430.jpg 323w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/figure>\n<\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;autorit\u00e9 en mati\u00e8re de foi et de m\u0153urs Abordons ce th\u00e8me de mani\u00e8re simple. Si on demandait \u00e0 un catholique instruit&nbsp;: \u00ab&nbsp;Pourquoi croyez-vous ceci ou cela&nbsp;?&nbsp;\u00bb, il r\u00e9pondrait&nbsp;: \u00ab&nbsp;Parce que l\u2019\u00c9glise l\u2019enseigne&nbsp;\u00bb. En disant cela, il exprime l\u2019optique catholique selon laquelle l\u2019autorit\u00e9 r\u00e9side, en dernier ressort, dans l\u2019\u00c9glise elle-m\u00eame. Si l\u2019on posait la m\u00eame question [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3385,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,72,68],"tags":[221,220,219,222,218],"class_list":["post-3383","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite","category-articles","category-extrait","tag-catholicisme","tag-catholique","tag-les-differences-entre-catholiques-et-protestants","tag-protestantisme","tag-william-clayton"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Diff\u00e9rence catholique \/ protestant : La question de l\u2019autorit\u00e9 (extrait du livre de William Clayton) - Blog des \u00c9ditions Cl\u00e9<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogs.editionscle.com\/blogcle\/difference-catholique-protestant-la-question-de-lautorite-extrait-du-livre-de-william-clayton\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Diff\u00e9rence catholique \/ protestant : La question de l\u2019autorit\u00e9 (extrait du livre de William Clayton) - Blog des \u00c9ditions Cl\u00e9\" \/>\n<meta property=\"og:description\" content=\"L&rsquo;autorit\u00e9 en mati\u00e8re de foi et de m\u0153urs Abordons ce th\u00e8me de mani\u00e8re simple. Si on demandait \u00e0 un catholique instruit&nbsp;: \u00ab&nbsp;Pourquoi croyez-vous ceci ou cela&nbsp;?&nbsp;\u00bb, il r\u00e9pondrait&nbsp;: \u00ab&nbsp;Parce que l\u2019\u00c9glise l\u2019enseigne&nbsp;\u00bb. En disant cela, il exprime l\u2019optique catholique selon laquelle l\u2019autorit\u00e9 r\u00e9side, en dernier ressort, dans l\u2019\u00c9glise elle-m\u00eame. Si l\u2019on posait la m\u00eame question [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogs.editionscle.com\/blogcle\/difference-catholique-protestant-la-question-de-lautorite-extrait-du-livre-de-william-clayton\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog des \u00c9ditions Cl\u00e9\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/editionscle\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-21T14:45:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-21T15:05:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2026\/01\/akira-hojo-_86u_Y0oAaM-unsplash-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"\u00c9ditions Cl\u00e9\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@editionscle\" \/>\n<meta name=\"twitter:site\" content=\"@editionscle\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u00c9ditions Cl\u00e9\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/difference-catholique-protestant-la-question-de-lautorite-extrait-du-livre-de-william-clayton\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/difference-catholique-protestant-la-question-de-lautorite-extrait-du-livre-de-william-clayton\\\/\"},\"author\":{\"name\":\"\u00c9ditions Cl\u00e9\",\"@id\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/#\\\/schema\\\/person\\\/6f614e2cdd8aac468261bff8219ca7a0\"},\"headline\":\"Diff\u00e9rence catholique \\\/ protestant : La question de l\u2019autorit\u00e9 (extrait du livre de William Clayton)\",\"datePublished\":\"2026-01-21T14:45:11+00:00\",\"dateModified\":\"2026-01-21T15:05:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/difference-catholique-protestant-la-question-de-lautorite-extrait-du-livre-de-william-clayton\\\/\"},\"wordCount\":1060,\"commentCount\":2,\"publisher\":{\"@id\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/difference-catholique-protestant-la-question-de-lautorite-extrait-du-livre-de-william-clayton\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/01\\\/akira-hojo-_86u_Y0oAaM-unsplash-scaled.jpg\",\"keywords\":[\"catholicisme\",\"catholique\",\"Les diff\u00e9rences entre catholiques et protestants\",\"protestantisme\",\"william Clayton\"],\"articleSection\":[\"Actualit\u00e9\",\"Articles\",\"Extrait\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/difference-catholique-protestant-la-question-de-lautorite-extrait-du-livre-de-william-clayton\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/difference-catholique-protestant-la-question-de-lautorite-extrait-du-livre-de-william-clayton\\\/\",\"url\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/difference-catholique-protestant-la-question-de-lautorite-extrait-du-livre-de-william-clayton\\\/\",\"name\":\"Diff\u00e9rence catholique \\\/ protestant : La question de l\u2019autorit\u00e9 (extrait du livre de William Clayton) - Blog des \u00c9ditions Cl\u00e9\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/difference-catholique-protestant-la-question-de-lautorite-extrait-du-livre-de-william-clayton\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/difference-catholique-protestant-la-question-de-lautorite-extrait-du-livre-de-william-clayton\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/01\\\/akira-hojo-_86u_Y0oAaM-unsplash-scaled.jpg\",\"datePublished\":\"2026-01-21T14:45:11+00:00\",\"dateModified\":\"2026-01-21T15:05:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/difference-catholique-protestant-la-question-de-lautorite-extrait-du-livre-de-william-clayton\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/difference-catholique-protestant-la-question-de-lautorite-extrait-du-livre-de-william-clayton\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/difference-catholique-protestant-la-question-de-lautorite-extrait-du-livre-de-william-clayton\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/01\\\/akira-hojo-_86u_Y0oAaM-unsplash-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/01\\\/akira-hojo-_86u_Y0oAaM-unsplash-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"Photo de Akira Hojo sur Unsplash\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/difference-catholique-protestant-la-question-de-lautorite-extrait-du-livre-de-william-clayton\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Diff\u00e9rence catholique \\\/ protestant : La question de l\u2019autorit\u00e9 (extrait du livre de William Clayton)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/#website\",\"url\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/\",\"name\":\"Blog des \u00c9ditions Cl\u00e9\",\"description\":\"Livres et logiciels pour comprendre la Bible\",\"publisher\":{\"@id\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/#organization\",\"name\":\"Editions Cl\u00e9\",\"url\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/03\\\/Profil_facebookcle.png\",\"contentUrl\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/03\\\/Profil_facebookcle.png\",\"width\":375,\"height\":375,\"caption\":\"Editions Cl\u00e9\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/editionscle\",\"https:\\\/\\\/x.com\\\/editionscle\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/EditionsCle\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blogs.editionscle.com\\\/blogcle\\\/#\\\/schema\\\/person\\\/6f614e2cdd8aac468261bff8219ca7a0\",\"name\":\"\u00c9ditions Cl\u00e9\",\"description\":\"\u00c9ditions Cl\u00e9\",\"sameAs\":[\"https:\\\/\\\/editionscle.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Diff\u00e9rence catholique \/ protestant : La question de l\u2019autorit\u00e9 (extrait du livre de William Clayton) - Blog des \u00c9ditions Cl\u00e9","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogs.editionscle.com\/blogcle\/difference-catholique-protestant-la-question-de-lautorite-extrait-du-livre-de-william-clayton\/","og_locale":"fr_FR","og_type":"article","og_title":"Diff\u00e9rence catholique \/ protestant : La question de l\u2019autorit\u00e9 (extrait du livre de William Clayton) - Blog des \u00c9ditions Cl\u00e9","og_description":"L&rsquo;autorit\u00e9 en mati\u00e8re de foi et de m\u0153urs Abordons ce th\u00e8me de mani\u00e8re simple. Si on demandait \u00e0 un catholique instruit&nbsp;: \u00ab&nbsp;Pourquoi croyez-vous ceci ou cela&nbsp;?&nbsp;\u00bb, il r\u00e9pondrait&nbsp;: \u00ab&nbsp;Parce que l\u2019\u00c9glise l\u2019enseigne&nbsp;\u00bb. En disant cela, il exprime l\u2019optique catholique selon laquelle l\u2019autorit\u00e9 r\u00e9side, en dernier ressort, dans l\u2019\u00c9glise elle-m\u00eame. Si l\u2019on posait la m\u00eame question [&hellip;]","og_url":"https:\/\/blogs.editionscle.com\/blogcle\/difference-catholique-protestant-la-question-de-lautorite-extrait-du-livre-de-william-clayton\/","og_site_name":"Blog des \u00c9ditions Cl\u00e9","article_publisher":"https:\/\/www.facebook.com\/editionscle","article_published_time":"2026-01-21T14:45:11+00:00","article_modified_time":"2026-01-21T15:05:50+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2026\/01\/akira-hojo-_86u_Y0oAaM-unsplash-scaled.jpg","type":"image\/jpeg"}],"author":"\u00c9ditions Cl\u00e9","twitter_card":"summary_large_image","twitter_creator":"@editionscle","twitter_site":"@editionscle","twitter_misc":{"\u00c9crit par":"\u00c9ditions Cl\u00e9","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blogs.editionscle.com\/blogcle\/difference-catholique-protestant-la-question-de-lautorite-extrait-du-livre-de-william-clayton\/#article","isPartOf":{"@id":"https:\/\/blogs.editionscle.com\/blogcle\/difference-catholique-protestant-la-question-de-lautorite-extrait-du-livre-de-william-clayton\/"},"author":{"name":"\u00c9ditions Cl\u00e9","@id":"https:\/\/blogs.editionscle.com\/blogcle\/#\/schema\/person\/6f614e2cdd8aac468261bff8219ca7a0"},"headline":"Diff\u00e9rence catholique \/ protestant : La question de l\u2019autorit\u00e9 (extrait du livre de William Clayton)","datePublished":"2026-01-21T14:45:11+00:00","dateModified":"2026-01-21T15:05:50+00:00","mainEntityOfPage":{"@id":"https:\/\/blogs.editionscle.com\/blogcle\/difference-catholique-protestant-la-question-de-lautorite-extrait-du-livre-de-william-clayton\/"},"wordCount":1060,"commentCount":2,"publisher":{"@id":"https:\/\/blogs.editionscle.com\/blogcle\/#organization"},"image":{"@id":"https:\/\/blogs.editionscle.com\/blogcle\/difference-catholique-protestant-la-question-de-lautorite-extrait-du-livre-de-william-clayton\/#primaryimage"},"thumbnailUrl":"https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2026\/01\/akira-hojo-_86u_Y0oAaM-unsplash-scaled.jpg","keywords":["catholicisme","catholique","Les diff\u00e9rences entre catholiques et protestants","protestantisme","william Clayton"],"articleSection":["Actualit\u00e9","Articles","Extrait"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blogs.editionscle.com\/blogcle\/difference-catholique-protestant-la-question-de-lautorite-extrait-du-livre-de-william-clayton\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blogs.editionscle.com\/blogcle\/difference-catholique-protestant-la-question-de-lautorite-extrait-du-livre-de-william-clayton\/","url":"https:\/\/blogs.editionscle.com\/blogcle\/difference-catholique-protestant-la-question-de-lautorite-extrait-du-livre-de-william-clayton\/","name":"Diff\u00e9rence catholique \/ protestant : La question de l\u2019autorit\u00e9 (extrait du livre de William Clayton) - Blog des \u00c9ditions Cl\u00e9","isPartOf":{"@id":"https:\/\/blogs.editionscle.com\/blogcle\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blogs.editionscle.com\/blogcle\/difference-catholique-protestant-la-question-de-lautorite-extrait-du-livre-de-william-clayton\/#primaryimage"},"image":{"@id":"https:\/\/blogs.editionscle.com\/blogcle\/difference-catholique-protestant-la-question-de-lautorite-extrait-du-livre-de-william-clayton\/#primaryimage"},"thumbnailUrl":"https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2026\/01\/akira-hojo-_86u_Y0oAaM-unsplash-scaled.jpg","datePublished":"2026-01-21T14:45:11+00:00","dateModified":"2026-01-21T15:05:50+00:00","breadcrumb":{"@id":"https:\/\/blogs.editionscle.com\/blogcle\/difference-catholique-protestant-la-question-de-lautorite-extrait-du-livre-de-william-clayton\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blogs.editionscle.com\/blogcle\/difference-catholique-protestant-la-question-de-lautorite-extrait-du-livre-de-william-clayton\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blogs.editionscle.com\/blogcle\/difference-catholique-protestant-la-question-de-lautorite-extrait-du-livre-de-william-clayton\/#primaryimage","url":"https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2026\/01\/akira-hojo-_86u_Y0oAaM-unsplash-scaled.jpg","contentUrl":"https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2026\/01\/akira-hojo-_86u_Y0oAaM-unsplash-scaled.jpg","width":2560,"height":1707,"caption":"Photo de Akira Hojo sur Unsplash"},{"@type":"BreadcrumbList","@id":"https:\/\/blogs.editionscle.com\/blogcle\/difference-catholique-protestant-la-question-de-lautorite-extrait-du-livre-de-william-clayton\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/blogs.editionscle.com\/blogcle\/"},{"@type":"ListItem","position":2,"name":"Diff\u00e9rence catholique \/ protestant : La question de l\u2019autorit\u00e9 (extrait du livre de William Clayton)"}]},{"@type":"WebSite","@id":"https:\/\/blogs.editionscle.com\/blogcle\/#website","url":"https:\/\/blogs.editionscle.com\/blogcle\/","name":"Blog des \u00c9ditions Cl\u00e9","description":"Livres et logiciels pour comprendre la Bible","publisher":{"@id":"https:\/\/blogs.editionscle.com\/blogcle\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogs.editionscle.com\/blogcle\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/blogs.editionscle.com\/blogcle\/#organization","name":"Editions Cl\u00e9","url":"https:\/\/blogs.editionscle.com\/blogcle\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blogs.editionscle.com\/blogcle\/#\/schema\/logo\/image\/","url":"https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2018\/03\/Profil_facebookcle.png","contentUrl":"https:\/\/blogs.editionscle.com\/blogcle\/wp-content\/uploads\/sites\/2\/2018\/03\/Profil_facebookcle.png","width":375,"height":375,"caption":"Editions Cl\u00e9"},"image":{"@id":"https:\/\/blogs.editionscle.com\/blogcle\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/editionscle","https:\/\/x.com\/editionscle","https:\/\/www.youtube.com\/user\/EditionsCle"]},{"@type":"Person","@id":"https:\/\/blogs.editionscle.com\/blogcle\/#\/schema\/person\/6f614e2cdd8aac468261bff8219ca7a0","name":"\u00c9ditions Cl\u00e9","description":"\u00c9ditions Cl\u00e9","sameAs":["https:\/\/editionscle.com"]}]}},"_links":{"self":[{"href":"https:\/\/blogs.editionscle.com\/blogcle\/wp-json\/wp\/v2\/posts\/3383","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.editionscle.com\/blogcle\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.editionscle.com\/blogcle\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.editionscle.com\/blogcle\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.editionscle.com\/blogcle\/wp-json\/wp\/v2\/comments?post=3383"}],"version-history":[{"count":7,"href":"https:\/\/blogs.editionscle.com\/blogcle\/wp-json\/wp\/v2\/posts\/3383\/revisions"}],"predecessor-version":[{"id":3398,"href":"https:\/\/blogs.editionscle.com\/blogcle\/wp-json\/wp\/v2\/posts\/3383\/revisions\/3398"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.editionscle.com\/blogcle\/wp-json\/wp\/v2\/media\/3385"}],"wp:attachment":[{"href":"https:\/\/blogs.editionscle.com\/blogcle\/wp-json\/wp\/v2\/media?parent=3383"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.editionscle.com\/blogcle\/wp-json\/wp\/v2\/categories?post=3383"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.editionscle.com\/blogcle\/wp-json\/wp\/v2\/tags?post=3383"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}